{"id":1835,"date":"2014-04-04T13:51:24","date_gmt":"2014-04-04T15:51:24","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/timcarriker\/?p=1835"},"modified":"2014-04-01T13:55:34","modified_gmt":"2014-04-01T15:55:34","slug":"as-viagens-missionarias-em-atos","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/timcarriker\/2014\/04\/04\/as-viagens-missionarias-em-atos\/","title":{"rendered":"As viagens mission\u00e1rias em Atos"},"content":{"rendered":"<blockquote><p>Resolvi dar uma pr\u00e9via da <em>B\u00edblia Mission\u00e1ria de Estudo<\/em> que ser\u00e1 lan\u00e7ada pela Sociedade B\u00edblica do Brasil por ocasi\u00e3o do Congresso Brasileiro de Miss\u00f5es em outubro deste ano. Segue-se uma das reflex\u00f5es que escrevi:<\/p><\/blockquote>\n<div>\n<p>A natureza do evangelho \u00e9 que seja divulgado. N\u00e3o se guarda boas novas para si. Divulga-se em alta voz. No s\u00e9culo I quando ainda n\u00e3o existiam os meios eletr\u00f4nicos de comunica\u00e7\u00e3o, isto implica na divulga\u00e7\u00e3o verbal, ou ao vivo ou por meio de documentos escritos. E a divulga\u00e7\u00e3o maior se fazia por meio de viagens. Por isto, tanto os Evangelhos quanto o Livro de Atos relatam a divulga\u00e7\u00e3o do evangelho por meio de viagens. Jesus deixava claro que as suas viagens eram necess\u00e1rias e vinculava esta necessidade a sua voca\u00e7\u00e3o do Pai (Lc 4.43). Por isso, nos Evangelhos, Jesus sempre se encontra em movimento. Sempre se encontra numa viagem. N\u00e3o se surpreende, portanto, que o evangelho se divulga no Livro de Atos tamb\u00e9m por meio de viagens.<\/p>\n<p>O Livro de Atos destaca as viagens mission\u00e1rias de Filipe, Pedro e especialmente Paulo, todos a partir de Jerusal\u00e9m como previsto pelo Senhor antes da sua assun\u00e7\u00e3o (1.8). Filipe partiu para Sebaste, a capital da Samaria (8.4-40). \u00a0Sua prega\u00e7\u00e3o era acompanhado de grandes sinais que causavam muita admira\u00e7\u00e3o e convers\u00f5es, inclusive Sim\u00e3o, um m\u00e1gico not\u00f3rio. Depois, Deus o dirigiu para o sul em dire\u00e7\u00e3o a Gaza onde pregou para o eunuco et\u00edope, um temente a Deus e oficial real que creu e foi batizado. Ainda prossegui para Azoto onde pregou e continuou o seu minist\u00e9rio at\u00e9 Cesareia.<\/p>\n<\/div>\n<p>Pedro viajou de Jerusal\u00e9m at\u00e9 Lida onde curou um paral\u00edtico, o que levou muitos na regi\u00e3o a crer (8.32-35). Depois, foi para Jafa onde ressuscitou uma mulher da morte (8.36-43). Enquanto Pedro foi hospedado na casa de Sime\u00e3o, o centuri\u00e3o romano, Corn\u00e9lio, mandou busc\u00e1-lo para ir a Cesareia (cap.10) o que abriu um novo cap\u00edtulo na evangeliza\u00e7\u00e3o com a inclus\u00e3o dos gentios.<\/p>\n<p>Mas Paulo batia todos os r\u00e9cordes no Livro de Atos que consta um total de seis viagens, todas a partir de Jerusal\u00e9m conforme o pr\u00f3prio punho de Paulo (Rm 15.19). Tantos os testemunhos de Paulo no Livro de Atos (22.21; 26.7, 17-18; 28.20.) quanto \u00e0s suas pr\u00f3prias palavras nas suas cartas (Gl 1.15-16; Rm 15.19-21) ressaltam a signific\u00e2ncia destas viagens dentro do grande esquema de salva\u00e7\u00e3o por Deus dos judeus e dos n\u00e3o-judeus.<\/p>\n<p>As viagens mission\u00e1rias eram essenciais para a divulga\u00e7\u00e3o do evangelho no s\u00e9culo I. Hoje ainda exercem um papel importante, mas tamb\u00e9m temos outros meios de comunica\u00e7\u00e3o mais abrangentes, penetrantes, r\u00e1pidos e econ\u00f4micos. As viagens mission\u00e1rias da B\u00edblia servem de modelo de como devemos explorar com integridade os meios de comunica\u00e7\u00e3o a nossa disposi\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resolvi dar uma pr\u00e9via da B\u00edblia Mission\u00e1ria de Estudo que ser\u00e1 lan\u00e7ada pela Sociedade B\u00edblica do Brasil por ocasi\u00e3o do Congresso Brasileiro de Miss\u00f5es em outubro deste ano. Segue-se uma das reflex\u00f5es que escrevi: A natureza do evangelho \u00e9 que seja divulgado. N\u00e3o se guarda boas novas para si. Divulga-se em alta voz. No s\u00e9culo [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":1839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[114,12041,12042],"tags":[],"class_list":["post-1835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-escritura-sagrada","category-fe-e-missao"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/posts\/1835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/comments?post=1835"}],"version-history":[{"count":6,"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/posts\/1835\/revisions"}],"predecessor-version":[{"id":1842,"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/posts\/1835\/revisions\/1842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/media\/1839"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/media?parent=1835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/categories?post=1835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/timcarriker\/wp-json\/wp\/v2\/tags?post=1835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}