{"id":445,"date":"2010-01-13T08:03:29","date_gmt":"2010-01-13T11:03:29","guid":{"rendered":"http:\/\/ultimato.com.br\/blogs\/paralelo10\/?p=445"},"modified":"2010-01-18T15:52:45","modified_gmt":"2010-01-18T18:52:45","slug":"seminario-intensivo-de-desenvolvimento-comunitario-sedec","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/paralelo10\/2010\/01\/seminario-intensivo-de-desenvolvimento-comunitario-sedec\/","title":{"rendered":"Semin\u00e1rio Intensivo de Desenvolvimento Comunit\u00e1rio &#8211; SEDEC"},"content":{"rendered":"<p align=\"CENTER\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-468\" style=\"margin: 10px;\" title=\"sedec\" src=\"http:\/\/ultimato.com.br\/blogs\/paralelo10\/files\/2010\/01\/sedec1.jpg\" alt=\"sedec\" width=\"212\" height=\"300\" \/><\/p>\n<p align=\"CENTER\">\n<p align=\"CENTER\"><span style=\"font-family: Verdana,sans-serif;\"><strong>25 a 29 de Janeiro, Felipe Camar\u00e3o, Natal, RN<\/strong><\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Preletores:<\/strong><\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><span style=\"font-style: normal;\"><strong>Mauricio Cunha<\/strong><\/span><span style=\"font-style: normal;\"> <\/span>\u2013 Diretor de Programas da Vis\u00e3o Mundial Brasil<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><span style=\"font-style: normal;\"><strong>Marcel Lins Camargo<\/strong><\/span> \u2013 Diretor do Centro de Desenvolvimento e Assist\u00eancia Integral (Fazenda Rio Grande &#8211; PR)<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Promo\u00e7\u00e3o:<\/strong><\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\">ALEF \u2013 Associa\u00e7\u00e3o de L\u00edderes Evang\u00e9licos de Felipe Camar\u00e3o, Vis\u00e3o Mundial e Rede Fale\/ Natal<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><!--more--><br \/>\n<\/span><\/p>\n<p><img decoding=\"async\" title=\"Mais...\" src=\"http:\/\/ultimato.com.br\/blogs\/paralelo10\/wp-includes\/js\/tinymce\/plugins\/wordpress\/img\/trans.gif\" alt=\"\" \/><span style=\"font-family: Verdana,sans-serif;\"><strong>Objetivo:<img loading=\"lazy\" decoding=\"async\" src=\"..\/wp-includes\/js\/tinymce\/plugins\/wordpress\/img\/trans.gif\" border=\"0\" alt=\"\" width=\"1\" height=\"1\" align=\"BOTTOM\" \/> <\/strong><\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\">O <strong>Semin\u00e1rio Intensivo de Desenvolvimento Comunit\u00e1rio<\/strong> (SEDEC) visa despertar as lideran\u00e7as locais para a tarefa de transforma\u00e7\u00e3o das comunidades empobrecidas, equipando l\u00edderes ao minist\u00e9rio de desenvolvimento integral. <\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\">O SEDEC \u00e9 um curso intensivo de uma semana direcionado a organiza\u00e7\u00f5es, igrejas e indiv\u00edduos que desejam atuar na \u00e1rea de desenvolvimento comunit\u00e1rio.<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Programa:<\/strong><\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\">O SEDEC possui duas etapas: a te\u00f3rica e a pr\u00e1tica. Na etapa te\u00f3rica do curso ser\u00e3o tratados temas como <span style=\"font-style: normal;\">&#8220;Cosmovis\u00e3o Crist\u00e3 e Transforma\u00e7\u00e3o&#8221;,<\/span> <span style=\"font-style: normal;\">&#8220;Base B\u00edblica da A\u00e7\u00e3o Social Crist\u00e3&#8221;<\/span>, <em>&#8220;<\/em><span style=\"font-style: normal;\">Princ\u00edpios de Desenvolvimento Comunit\u00e1rio&#8221;<\/span>, <em>&#8220;<\/em><span style=\"font-style: normal;\">Os pobres de Deus &#8211; uma breve an\u00e1lise b\u00edblica sobre os pobres&#8221;, &#8220;Tipos de Ajuda&#8221;, \u201cEspiando a Terra \u2013 conhecendo a comunidade\u201d, dentre outros. <\/span><\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\">A \u00e1rea pr\u00e1tica, que ocupa aproximadamente 40% da semana, ser\u00e1 por meio do <strong>Projeto Semente<\/strong>, uma ferramenta de planejamento de pequenas interven\u00e7\u00f5es de servi\u00e7o pr\u00e1tico na comunidade. Os estudantes do curso s\u00e3o divididos em grupos de at\u00e9 10, e ensinados a efetuar o planejamento nos moldes do Projeto Semente\/PDA. A seguir eles dever\u00e3o executar o projeto nas comunidades do bairro.<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Carga Hor\u00e1ria:<\/strong> 60 horas\/aula \u2013 01 semana de curso<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Vagas: <\/strong><span style=\"font-weight: normal;\">50<\/span><\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Investimento:<\/strong> R$ 150,00 &#8211; Inscri\u00e7\u00e3o (com direito a todas as refei\u00e7\u00f5es,\u00a0certificado,\u00a0material did\u00e1tico e hospedagem\u00a0opcional).<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Informa\u00e7\u00f5es:<\/strong><\/span><span style=\"font-family: Verdana,sans-serif;\"> Leandro e-mail: <a href=\"mailto:leandro_amme@yahoo.com.br\">leandro_amme@yahoo.com.br<\/a> <\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"> ou pelo telefone: (84) 9630-5445.<\/span><\/p>\n<p><span style=\"font-family: Verdana,sans-serif;\"><strong>Obs: <\/strong>In\u00edcio da programa\u00e7\u00e3o \u00e0s 08h do dia 25\/01 encerramento no dia 29\/01 as 12h.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>25 a 29 de Janeiro, Felipe Camar\u00e3o, Natal, RN Preletores: Mauricio Cunha \u2013 Diretor de Programas da Vis\u00e3o Mundial Brasil Marcel Lins Camargo \u2013 Diretor do Centro de Desenvolvimento e Assist\u00eancia Integral (Fazenda Rio Grande &#8211; PR) Promo\u00e7\u00e3o: ALEF \u2013 Associa\u00e7\u00e3o de L\u00edderes Evang\u00e9licos de Felipe Camar\u00e3o, Vis\u00e3o Mundial e Rede Fale\/ Natal<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[101,100,46,26,82,45],"class_list":["post-445","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-cadi","tag-desenvolvimento-comunitario","tag-mauricio-cunha","tag-missao-integral","tag-natal","tag-visao-mundial"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts\/445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/comments?post=445"}],"version-history":[{"count":5,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts\/445\/revisions"}],"predecessor-version":[{"id":449,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts\/445\/revisions\/449"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/media?parent=445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/categories?post=445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/tags?post=445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}