{"id":3461,"date":"2013-12-18T08:00:48","date_gmt":"2013-12-18T11:00:48","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/paralelo10\/?p=3461"},"modified":"2013-12-16T14:47:20","modified_gmt":"2013-12-16T17:47:20","slug":"defendido-o-primeiro-tcc-de-um-aluno-indigena-na-ufpa","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/paralelo10\/2013\/12\/defendido-o-primeiro-tcc-de-um-aluno-indigena-na-ufpa\/","title":{"rendered":"Defendido o primeiro TCC de um aluno ind\u00edgena na UFPA"},"content":{"rendered":"<p><a href=\"http:\/\/ultimato.com.br\/sites\/paralelo10\/files\/2013\/12\/tcc_indigena.jpg\" class=\"lightview\" data-lightview-group=\"group-3461\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3462\" alt=\"tcc_indigena\" src=\"http:\/\/ultimato.com.br\/sites\/paralelo10\/files\/2013\/12\/tcc_indigena-300x176.jpg\" width=\"300\" height=\"176\" srcset=\"https:\/\/ultimato.com.br\/sites\/paralelo10\/files\/2013\/12\/tcc_indigena-300x176.jpg 300w, https:\/\/ultimato.com.br\/sites\/paralelo10\/files\/2013\/12\/tcc_indigena-150x88.jpg 150w, https:\/\/ultimato.com.br\/sites\/paralelo10\/files\/2013\/12\/tcc_indigena.jpg 421w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Um momento hist\u00f3rico para a Universidade Federal do Par\u00e1. Foi realizada,\u00a0no dia 12, a primeira defesa de Trabalho de Conclus\u00e3o de Curso (TCC) de um estudante ind\u00edgena na Institui\u00e7\u00e3o. O discente da etnia Temb\u00e9, Jorge Alberto Sarmento dos Santos, defendeu o trabalho intitulado \u201cContabilidade em Institui\u00e7\u00e3o Ind\u00edgena: um estudo da presta\u00e7\u00e3o de contas da Associa\u00e7\u00e3o do Grupo Ind\u00edgena Temb\u00e9 das Aldeias Sede e Itua\u00e7u (Agitasi)\u201d.<\/p>\n<p>A defesa ocorreu no Instituto de Ci\u00eancias Sociais Aplicadas (Icsa) da UFPA. O estudante recebeu conceito excelente e ir\u00e1 se formar em Ci\u00eancias Cont\u00e1beis. O estudo mostra como a contabilidade pode ajudar na administra\u00e7\u00e3o da Associa\u00e7\u00e3o Agitasi, das aldeias Temb\u00e9, a fim de contribuir para sua melhoria.<!--more--><\/p>\n<p><strong>Presta\u00e7\u00e3o de contas &#8211;<\/strong> O presidente da Associa\u00e7\u00e3o dos Povos Ind\u00edgenas Estudantes da UFPA, professor Edimar Fernandes, comentou as dificuldades enfrentadas por esses povos em rela\u00e7\u00e3o ao tema levantado pelas pesquisas de Jorge Alberto. \u201cEsses povos enfrentam v\u00e1rios problemas com a presta\u00e7\u00e3o de contas de diversos projetos, al\u00e9m das contas financeiras da pr\u00f3pria associa\u00e7\u00e3o, que precisam ser feitas anualmente. A associa\u00e7\u00e3o existe, por\u00e9m \u00e9 preciso fazer com que ela continue funcionando e, para isso, \u00e9 necess\u00e1rio que ela se adapte \u00e0s legisla\u00e7\u00f5es e normas existentes da sociedade n\u00e3o ind\u00edgena, j\u00e1 que a associa\u00e7\u00e3o n\u00e3o \u00e9 uma ferramenta que faz parte da cultura ind\u00edgena\u201d, explicou.<\/p>\n<p><strong>Acesso ao Ensino Superior<\/strong> &#8211; Em todo o Par\u00e1, existem cerca de 60 povos ind\u00edgenas. Para possibilitar o acesso de ind\u00edgenas ao ensino superior, a UFPA realiza, desde 2010, o Processo Seletivo Especial para Povos Ind\u00edgenas, para o qual a Universidade destina duas vagas a mais em todos os cursos de gradua\u00e7\u00e3o da Institui\u00e7\u00e3o a candidatos de origem ind\u00edgenas.<\/p>\n<p><strong>Marco &#8211;<\/strong> \u201cEste \u00e9 um marco para a Universidade, porque \u00e9 o primeiro ind\u00edgena a se formar a partir de um programa da Institui\u00e7\u00e3o. Ele s\u00f3 est\u00e1 aqui porque foi criado um programa que facilitou o seu acesso ao conhecimento, o qual foi criado, tamb\u00e9m, a partir das solicita\u00e7\u00f5es dos povos ind\u00edgenas. Esta \u00e9 mais uma conquista que n\u00f3s tivemos, pois \u00e9 justamente o ensino superior que nos permite ganhar novas lideran\u00e7as para compor nossos quadros de funcionalismo. Sair daqui com o diploma em m\u00e3os \u00e9, tamb\u00e9m, a possibilidade de cumprirmos com o nosso papel de cidad\u00e3o, como ind\u00edgena , para a nossa aldeia e os nossos povos\u201d, disse Edimar Fernandes.<\/p>\n<p>Para o futuro contador Jorge Alberto Santos, \u201c\u00e9 uma realiza\u00e7\u00e3o tanto pessoal quanto profissional e, ainda, uma realiza\u00e7\u00e3o para o povo ind\u00edgena. Eu vim indicado pelos meus parentes e pelos caciques da minha aldeia, e sempre procurei cumprir tudo direito, dando o meu melhor, pois tem o meu povo que confia em mim, eu n\u00e3o podia desapont\u00e1-los. Gra\u00e7as a Deus deu tudo certo, finalizei o curso com este conceito excelente, espero levar esses conhecimentos para l\u00e1 e trabalhar na minha comunidade. S\u00f3 quero voltar para minha aldeia, pois n\u00e3o aguento mais a cidade!\u201d, falou em tom saudosista o ind\u00edgena de origem Temb\u00e9.<\/p>\n<p><strong>Incentivos &#8211;<\/strong> Al\u00e9m do Processo Seletivo, a UFPA tamb\u00e9m oferece alguns incentivos para a perman\u00eancia dos estudantes de origem ind\u00edgena, como o Programa Aux\u00edlio Perman\u00eancia Estudantil Especial, que visa atender demandas, como moradia, transporte, alimenta\u00e7\u00e3o e aquisi\u00e7\u00e3o de material did\u00e1tico. Os alunos ind\u00edgenas podem, tamb\u00e9m, solicitar \u00e0 Institui\u00e7\u00e3o alimenta\u00e7\u00e3o gratuita no Restaurante Universit\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>__________<br \/>\nTexto: Beatriz Santos\/ Assessoria de Comunica\u00e7\u00e3o da UFPA. Foto: La\u00eds Teixeira<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um momento hist\u00f3rico para a Universidade Federal do Par\u00e1. Foi realizada,\u00a0no dia 12, a primeira defesa de Trabalho de Conclus\u00e3o de Curso (TCC) de um estudante ind\u00edgena na Institui\u00e7\u00e3o. O discente da etnia Temb\u00e9, Jorge Alberto Sarmento dos Santos, defendeu o trabalho intitulado \u201cContabilidade em Institui\u00e7\u00e3o Ind\u00edgena: um estudo da presta\u00e7\u00e3o de contas da Associa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[12,122],"class_list":["post-3461","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-indigenas","tag-norte"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts\/3461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/comments?post=3461"}],"version-history":[{"count":2,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts\/3461\/revisions"}],"predecessor-version":[{"id":3464,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/posts\/3461\/revisions\/3464"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/media?parent=3461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/categories?post=3461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/paralelo10\/wp-json\/wp\/v2\/tags?post=3461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}