{"id":9569,"date":"2025-03-14T12:10:49","date_gmt":"2025-03-14T15:10:49","guid":{"rendered":"https:\/\/ultimato.com.br\/sites\/jovem\/?p=9569"},"modified":"2025-03-17T10:41:43","modified_gmt":"2025-03-17T13:41:43","slug":"um-chamado-a-espiritualidade-encarnada","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2025\/03\/14\/um-chamado-a-espiritualidade-encarnada\/","title":{"rendered":"Um chamado \u00e0 espiritualidade encarnada"},"content":{"rendered":"<blockquote><p>A f\u00e9 que me mobilizava tamb\u00e9m me impulsionava a ir al\u00e9m<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #808000;\"><strong>Por D\u00e1lethe Melissa<\/strong><\/span><\/p>\n<p><span style=\"color: #993300;\"><strong>O Meu Lugar no Mundo<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-9572\" src=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/03\/blog_jovem_13-3-25_omlm-300x222.jpg\" alt=\"\" width=\"350\" height=\"259\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/03\/blog_jovem_13-3-25_omlm-300x222.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/03\/blog_jovem_13-3-25_omlm.jpg 500w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>Compreender qual o meu lugar no mundo n\u00e3o foi uma tarefa f\u00e1cil. Falar sobre isso \u00e9 falar sobre <a href=\"https:\/\/loja.ultimato.com.br\/livros\/o-discipulo-radical\">como a dimens\u00e3o de uma espiritualidade encarnada no ch\u00e3o da vida transformou o meu modo de viver<\/a>.<\/p>\n<p>Cresci em um lar crist\u00e3o evang\u00e9lico, rodeada de familiares que participavam intensamente das din\u00e2micas eclesi\u00e1sticas e das responsabilidades que isso trazia, mas um inc\u00f4modo sempre esteve presente, que hoje pode ser traduzido em indaga\u00e7\u00f5es como: <a href=\"https:\/\/loja.ultimato.com.br\/livros\/quando-a-igreja-abraca-a-cidade\">Por que n\u00e3o nos envolvemos com o que acontece nas nossas comunidades?<\/a> Mesmo inseridos fisicamente no territ\u00f3rio, por que h\u00e1 uma dist\u00e2ncia que nos aparta da realidade concreta que nos rodeia?<\/p>\n<p>Esse inc\u00f4modo persistiu por um tempo, me fazendo questionar o papel da minha f\u00e9, o sentido da espiritualidade e o real significado da miss\u00e3o da Igreja. Eu n\u00e3o conseguia conceber que todas as \u2018\u2019boas obras\u2019\u2019 as quais Deus preparou para n\u00f3s praticarmos (Ef 2.10) se resumiria a manuten\u00e7\u00e3o de uma estrutura eclesi\u00e1stica, ou at\u00e9 mesmo ao servi\u00e7o de uma doutrina institucionalizada. <a href=\"https:\/\/loja.ultimato.com.br\/livros\/o-discipulo-radical\">A f\u00e9 que me mobilizava, tamb\u00e9m me impulsionava a ir al\u00e9m<\/a>, e assim eu me vi em uma jornada de encontro com o verdadeiro Evangelho, possibilitando a constru\u00e7\u00e3o de um real sentido para a minha exist\u00eancia.<\/p>\n<p>Esse encontro se deu quando eu passei a enxergar o mundo com um olhar mais cr\u00edtico, questionando suas estruturas injustas e desiguais, seus sistemas de opress\u00e3o e seus projetos hegem\u00f4nicos de poder que precarizam a vida, vulnerabilizam comunidades, violentam corpos e degradam territ\u00f3rios. Essa lente me foi proporcionada a partir da leitura popular da B\u00edblia, que atrav\u00e9s de uma interpreta\u00e7\u00e3o cr\u00edtica me fez compreender que essa \u00e9 uma realidade que se contrap\u00f5e ao projeto do Reino de Deus, que se trata do estabelecimento da Justi\u00e7a, Paz e Alegria no Esp\u00edrito Santo (Rm 14.17).<\/p>\n<p>Ao entender que esse projeto est\u00e1 fundamentado na promo\u00e7\u00e3o da vida plena que Jesus de Nazar\u00e9 anunciou (Jo 10.10), que busca transformar a vida na sua integralidade, percebi que <a href=\"https:\/\/loja.ultimato.com.br\/livros\/quando-a-igreja-abraca-a-cidade\">o exerc\u00edcio da minha f\u00e9 tamb\u00e9m tinha um compromisso coletivo e comunit\u00e1rio, n\u00e3o podendo estar dissociada da luta por justi\u00e7a, dignidade e equidade<\/a>. Percebi que a viv\u00eancia da espiritualidade n\u00e3o se trata da conserva\u00e7\u00e3o de uma religiosidade vazia, que se aparta da realidade, mas sim que se envolve e se debru\u00e7a nela, compreendendo a materializa\u00e7\u00e3o da f\u00e9 encarnada na vida concreta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-9562 size-thumbnail\" src=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/02\/selo_meulugarnomundo-01-01-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/>A partir disso, eu mudei os meus objetivos pessoais e profissionais, e \u00e1vida por empenhar a minha vida na proclama\u00e7\u00e3o desse Reino, passei a me envolver ativamente em iniciativas crist\u00e3s que se dedicam na defesa de direitos, na luta em favor da democracia e dos povos oprimidos, na den\u00fancia das injusti\u00e7as e na busca por uma coexist\u00eancia harm\u00f4nica entre toda a Cria\u00e7\u00e3o de Deus \u2013 que envolve seres humanos e n\u00e3o humanos. A minha igreja local \u2013 <a href=\"https:\/\/www.instagram.com\/ibcoqueiral\/\">Igreja Batista em Coqueiral<\/a> \u2013, o <a href=\"https:\/\/www.instagram.com\/forte.tejipio\/\">F\u00f3rum Popular do Rio Tejipi\u00f3 (FORTE)<\/a> e o <a href=\"https:\/\/www.instagram.com\/nos.nacriacao\/\">Instituto N\u00f3s na Cria\u00e7\u00e3o<\/a> s\u00e3o exemplos de espa\u00e7os que hoje ocupo e que me forjam nesse lugar, me ensinando diariamente a continuar nessa caminhada prof\u00e9tica, enquanto uma agente ativa do Reino de Deus, atuante em prol do bem comum, da vida plena, do <em>shalom<\/em>.<\/p>\n<p>Seja enquanto membro de uma igreja comunit\u00e1ria da periferia da Regi\u00e3o Metropolitana do Recife, ou enquanto uma futura assistente social que ir\u00e1 incidir na viabiliza\u00e7\u00e3o dos direitos sociais, Deus me mostrou que o meu lugar no mundo \u00e9 em qualquer lugar onde a minha espiritualidade \u00e9 encarnada e traduzida em pr\u00e1ticas de amor, resist\u00eancia e luta por justi\u00e7a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-9577\" src=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/03\/blog_jovem_13-3-25_omlm_1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/03\/blog_jovem_13-3-25_omlm_1-300x200.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/03\/blog_jovem_13-3-25_omlm_1.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<ul>\n<li><strong>D\u00e1lethe Melissa<\/strong>, mais conhecida por Mel, \u00e9 uma jovem recifense, estudante de Servi\u00e7o Social (UFPE), que trabalha no Instituto N\u00f3s na Cria\u00e7\u00e3o h\u00e1 3 anos. \u00c9 membro daIgreja Batista em Coqueiral (IBC), onde faz parte da sua Pastoral Ambiental, e tamb\u00e9m integra a Rede de Jovens L\u00edderes daAm\u00e9rica Latina e Caribe &#8211; Tearfund e o Comit\u00ea Executivo do F\u00f3rum Popular do Rio Tejipi\u00f3 (FORTE), se dedicando em espa\u00e7os que pensam o papel da f\u00e9 e a atua\u00e7\u00e3o das igrejas locais na luta por justi\u00e7a socioambiental.<\/li>\n<\/ul>\n<h5><\/h5>\n<h5><\/h5>\n<h5>Imagem: <a href=\"https:\/\/pixabay.com\/pt\/photos\/sapato-equil%C3%ADbrio-caminho-saldo-5422748\/\">Pixabay<\/a>.<\/h5>\n<hr \/>\n<h5><span style=\"color: #808000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9561\" src=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2025\/02\/Capa_19x25cm_ULT_412.jpg\" alt=\"\" width=\"115\" height=\"150\" \/>REVISTA ULTIMATO \u2013 COMO VIVEM OS QUE T\u00caM ESPERAN\u00c7A<\/strong><\/span><\/h5>\n<h5>Com a mat\u00e9ria <a href=\"https:\/\/www.ultimato.com.br\/revista\/\">\u201cComo vivem os que t\u00eam esperan\u00e7a\u201d<\/a>, <strong>Ultimato <\/strong>quer colocar Cristo no centro e enfatizar que a vida dos que t\u00eam esperan\u00e7a atrai outros para a Esperan\u00e7a. Quer lembrar que a comunidade dos que t\u00eam esperan\u00e7a deve ser uma ponte para aqueles que \u201cpassam por necessidades, cuja esperan\u00e7a para o futuro n\u00e3o \u00e9 sustentada pela experi\u00eancia de b\u00ean\u00e7\u00e3o no passado, que n\u00e3o conheceram cura, ou f\u00e9, ou prosperidade e que n\u00e3o t\u00eam esperan\u00e7a\u201d.<\/h5>\n<p>\u00c9 disso que trata a mat\u00e9ria de capa da <a href=\"https:\/\/www.ultimato.com.br\/revista\/\">edi\u00e7\u00e3o 412<\/a> da revista <strong>Ultimato<\/strong>. Para assinar, clique <a href=\"https:\/\/loja.ultimato.com.br\/categorias\/explore\/assine-a-revista\">aqui<\/a>.<\/p>\n<hr \/>\n<p><strong>Saiba mais:<\/strong><\/p>\n<p>&gt;&gt; <a href=\"https:\/\/loja.ultimato.com.br\/livros\/quando-a-igreja-abraca-a-cidade\">Quando a Igreja Abra\u00e7a a Cidade<\/a>, Leandro Silva (org.)<\/p>\n<p>&gt;&gt; <a href=\"https:\/\/loja.ultimato.com.br\/livros\/o-discipulo-radical\">O Disc\u00edpulo Radical<\/a>, John Stott<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A f\u00e9 que me mobilizava tamb\u00e9m me impulsionava a ir al\u00e9m &nbsp; Por D\u00e1lethe Melissa O Meu Lugar no Mundo Compreender qual o meu lugar no mundo n\u00e3o foi uma tarefa f\u00e1cil. Falar sobre isso \u00e9 falar sobre como a dimens\u00e3o de uma espiritualidade encarnada no ch\u00e3o da vida transformou o meu modo de viver. [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[34457,9],"tags":[73,5536,5681,30642,6062],"class_list":["post-9569","post","type-post","status-publish","format-standard","hentry","category-meu-lugar-no-mundo","category-sem-categoria","tag-comunidade","tag-fe","tag-justica","tag-o-meu-lugar-no-mundo","tag-trabalho"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/9569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=9569"}],"version-history":[{"count":7,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/9569\/revisions"}],"predecessor-version":[{"id":9580,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/9569\/revisions\/9580"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=9569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=9569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=9569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}