{"id":8265,"date":"2020-08-19T08:28:40","date_gmt":"2020-08-19T11:28:40","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/jovem\/?p=8265"},"modified":"2020-08-20T08:39:09","modified_gmt":"2020-08-20T11:39:09","slug":"o-silencio-dos-crentes","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2020\/08\/19\/o-silencio-dos-crentes\/","title":{"rendered":"O sil\u00eancio dos crentes"},"content":{"rendered":"<p><em>Por Lucas Peterson<\/em><\/p>\n<p id=\"0b99\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8267 alignright\" src=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-300x200.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-1024x684.jpg 1024w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-768x513.jpg 768w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-1536x1025.jpg 1536w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-2048x1367.jpg 2048w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-732x489.jpg 732w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/08\/UltJovem_19_08_20_silencio-1140x761.jpg 1140w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Tenho refletido nesses dias de isolamento sobre o sil\u00eancio conivente dos crentes.<\/p>\n<p id=\"b967\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">N\u00e3o s\u00e3o todos, voc\u00ea poder\u00e1 me alertar. De fato, n\u00e3o s\u00e3o todos, mas n\u00e3o s\u00e3o poucos.<\/p>\n<p id=\"6bb0\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">\u00c9 curioso, logo os crentes, que tanto defendem a bandeira da vida. N\u00e3o \u00e9 preciso esfor\u00e7o para recordar de como se indignam com a quest\u00e3o do aborto. Se mobilizam, protestam, se articulam. Mas, parece que outras mortes n\u00e3o os chocam tanto.<\/p>\n<p id=\"3340\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">N\u00e3o causa revolta, por exemplo, o assassinato do menino Jo\u00e3o Pedro, de 14 anos, negro, perif\u00e9rico, evang\u00e9lico (!). Morto pela for\u00e7a da viol\u00eancia do Estado. Morto pelas costas com um tiro de fuzil, enquanto brincava em casa, durante uma a\u00e7\u00e3o da Pol\u00edcia.<\/p>\n<p id=\"b2bb\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Sil\u00eancio!<!--more--><\/p>\n<p id=\"287e\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Os irm\u00e3os tamb\u00e9m ficam em sil\u00eancio, muitas vezes, e n\u00e3o levantam as suas vozes para combater o machismo. A assustadora realidade que revela que durante a pandemia as taxas de viol\u00eancia contra a mulher e de feminic\u00eddio aumentaram mais de 40% no estado de S\u00e3o Paulo. Logo os seguidores de Jesus, que impediu que a mulher ad\u00faltera fosse apedrejada (Jo\u00e3o 8), que perdoou os pecados da mulher pecadora e a ela deu salva\u00e7\u00e3o e paz (Lucas 7).<\/p>\n<p id=\"45ca\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Sil\u00eancio!<\/p>\n<p id=\"2a83\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">N\u00e3o ouvem os gritos de dor e de morte de tantos e tantas l\u00e9sbicas, gays, bissexuais, travestis, transexuais e transg\u00eaneros. Ser\u00e1 que o fato de entendermos que a B\u00edblia condena o pecado da \u201cpr\u00e1tica homossexual\u201d \u00e9 justificativa para n\u00e3o andarmos ao lado deles? Para n\u00e3o oferecermos ajuda, acolhimento? Para n\u00e3o conhecermos e partilharmos das suas dores? Afinal, se eles est\u00e3o em pecado, n\u00e3o foi justamente para eles que Jesus veio? Pois Ele mesmo disse que\u00a0<em class=\"kv\">n\u00e3o veio chamar justos, mas pecadores, ao arrependimento<\/em>\u00a0(Lucas 5:32).<\/p>\n<p id=\"8949\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Sil\u00eancio!<\/p>\n<p id=\"03d3\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Se calam diante da realidade de pobreza do nosso pa\u00eds. Uma realidade que, me perdoem a franqueza, \u00e9\u00a0<strong class=\"jz kw\"><em class=\"kv\">demon\u00edaca<\/em><\/strong>! Nosso pa\u00eds tem se mostrado incapaz de enfrentar a pandemia do novo coronav\u00edrus. Um pa\u00eds em que muitos sequer t\u00eam o direito de escolher praticar o isolamento em suas casas. Muitos nem t\u00eam uma casa. Lutam agora contra o frio e contra o v\u00edrus invis\u00edvel nas ruas das cidades. Outros tantos n\u00e3o t\u00eam dinheiro para ficar em casa. A fam\u00edlia grande, a falta de saneamento b\u00e1sico, os poucos c\u00f4modos do barraco, o aux\u00edlio do governo que n\u00e3o chega ou n\u00e3o basta, a comida que se esgota. Precisam sair pra trazer o p\u00e3o.<\/p>\n<p id=\"6687\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Sil\u00eancio!<\/p>\n<p id=\"d52f\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Basta!<\/p>\n<p id=\"d928\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">Um livro oportuno aos nossos dias \u00e9 o do profeta Am\u00f3s. Em que Deus revela que est\u00e1 farto dos cultos e das reuni\u00f5es religiosas do seu povo. Que n\u00e3o aguenta mais ouvir as mesmas musiquinhas todo domingo (cap. 5:21\u201323). Em vez disso, Ele deseja uma grande inunda\u00e7\u00e3o de\u00a0<strong class=\"jz kw\">JUSTI\u00c7A<\/strong>\u00a0e que um rio inesgot\u00e1vel de\u00a0<strong class=\"jz kw\">RETID\u00c3O<\/strong>\u00a0corra no meio do povo.<\/p>\n<p id=\"e85e\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">O livro come\u00e7a dizendo que &#8220;<em class=\"kv\">de Si\u00e3o o Senhor ruge&#8221;<\/em>. O texto compara Deus a um le\u00e3o e diz que do monte (Si\u00e3o) Ele ruge. O le\u00e3o ruge n\u00e3o depois de pegar a sua presa, mas ele ruge justamente antes disso19, para assustar a presa, para p\u00f4r medo no alvo do seu ataque. Alvo esse que o livro deixa bem claro que s\u00e3o os opressores, que s\u00e3o os causadores de tanta injusti\u00e7a.<\/p>\n<p id=\"3328\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">O Senhor da Igreja promete justi\u00e7a. O Senhor da Igreja promete p\u00f4r fim \u00e0s injusti\u00e7as. A todas elas.<\/p>\n<p id=\"dcaf\" class=\"jx jy bj jz b ka kb kc kd ke kf kg kh ki kj kk kl km kn ko kp kq kr ks kt ku hb ct\" data-selectable-paragraph=\"\">O rugido do le\u00e3o contrasta crua e duramente com o sil\u00eancio dos crentes.<\/p>\n<ul>\n<li><strong>Lucas Peterson Magalh\u00e3es<\/strong>, 27 anos. Formado em Direito, participa da Comunidade Evang\u00e9lica em S\u00e3o Bernardo do Campo (SP). Texto publicado originalmente em seu <a href=\"https:\/\/medium.com\/textando\/o-sil%C3%AAncio-dos-crentes-831a55627190\">Medium<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Por Lucas Peterson Tenho refletido nesses dias de isolamento sobre o sil\u00eancio conivente dos crentes. N\u00e3o s\u00e3o todos, voc\u00ea poder\u00e1 me alertar. De fato, n\u00e3o s\u00e3o todos, mas n\u00e3o s\u00e3o poucos. \u00c9 curioso, logo os crentes, que tanto defendem a bandeira da vida. N\u00e3o \u00e9 preciso esfor\u00e7o para recordar de como se indignam com a [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6054],"tags":[31885,42205],"class_list":["post-8265","post","type-post","status-publish","format-standard","hentry","category-textos","tag-lucas-peterson-magalhaes","tag-omissao"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/8265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=8265"}],"version-history":[{"count":2,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/8265\/revisions"}],"predecessor-version":[{"id":8268,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/8265\/revisions\/8268"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=8265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=8265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=8265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}