{"id":8167,"date":"2020-06-15T22:59:54","date_gmt":"2020-06-16T01:59:54","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/jovem\/?p=8167"},"modified":"2020-06-15T22:59:54","modified_gmt":"2020-06-16T01:59:54","slug":"o-tempo-pra-todas-as-coisas-inclusive-as-que-a-gente-nao-gosta","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2020\/06\/15\/o-tempo-pra-todas-as-coisas-inclusive-as-que-a-gente-nao-gosta\/","title":{"rendered":"O tempo pra todas as coisas, inclusive as que a gente n\u00e3o gosta"},"content":{"rendered":"<p><em>Gabriela Prillip<\/em><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-8169\" src=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-300x200.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-1024x683.jpg 1024w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-768x512.jpg 768w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-1536x1024.jpg 1536w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-2048x1365.jpg 2048w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-732x488.jpg 732w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2020\/06\/UltJovem_15_06_20_tempo-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>N\u00e3o \u00e9 um momento f\u00e1cil e a gente j\u00e1 cansou de trag\u00e9dia e tristeza pra saber disso, todo mundo fala isso o tempo todo. Eu j\u00e1 cansei de novo s\u00f3 de escrever aqui. A vida muitas vezes parece injusta e \u00e9; parece um sofrimento e caos sem fim e as vezes \u00e9 mesmo. E vai ser por mais tempo. E digo isso sem medo e sem spoiler nenhum, afinal voc\u00ea pode conferir cada epis\u00f3dio dessa grande narrativa na B\u00edblia e talvez te fa\u00e7a lembrar que a nossa hist\u00f3ria n\u00e3o \u00e9 bem nossa e que fazemos parte de uma narrativa bem maior, que pouco tem a ver com a gente, mas onde somos personagens bem ativos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Um dia desses foi meu anivers\u00e1rio e algu\u00e9m me perguntou se eu estava feliz, porque costumo ser a pessoa que fica insuportavelmente alegre nessa data. E n\u00e3o, eu n\u00e3o estava feliz. E fiquei meio feliz com isso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A gente veio de uma onda em que ser feliz \u00e9 palavra de ordem seja em algumas igrejas, no trabalho, carreira, planos de vida, enfim, como sociedade, uma cobran\u00e7a excessiva e sem cabimento de uma felicidade que n\u00e3o \u00e9 poss\u00edvel alcan\u00e7ar. E nem \u00e9 poss\u00edvel ser feliz, leve, de bem com a vida e<em> good vibes<\/em> exalando arco-\u00edris e purpurina por onde passa em todo o tempo. <\/span><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">A \u00fanica coisa que \u00e9 o tempo todo \u00e9 Deus, que sim, \u00e9 bom o tempo todo; j\u00e1 a gente n\u00e3o tem como sustentar essa felicidade em todo momento, sinto em te dizer tamb\u00e9m. Byung-Chul Han tamb\u00e9m sente em dizer, de alguma forma, que essa leveza que n\u00e3o se sustenta por muito tempo s\u00f3 causa uma sociedade cada vez mais cansada e psicologicamente doente. E a gente sabe que \u00e9 verdade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo que seja por s\u00f3 um momento, vamos confessar que entramos nessa pira tamb\u00e9m. Poxa, como assim n\u00e3o vamos ser felizes? Pera\u00ed&#8230; ainda mais a gente, crist\u00e3o, poxa vida n\u00e9, n\u00e3o rola! Mas, como crist\u00e3o, a gente tamb\u00e9m deveria nunca esquecer que h\u00e1 tempo pra tudo e literalmente tudo: tempo de ser feliz, tempo de chorar e lamentar. E acho que a gente se encontra nesse \u00faltimo est\u00e1gio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fiquei feliz de n\u00e3o estar feliz com algo que era significativo pra mim, pois nesse momento do mundo em que a gente se encontra, seria cruel e at\u00e9 meio errado. Ver pessoas sofrendo, morrendo&#8230; n\u00e3o tem como ser feliz ou positivo e sempre bom lembrar: f\u00e9 em Deus n\u00e3o tem nada a ver com positividade. \u00c9<\/span> <span style=\"font-weight: 400;\">tempo de lamento, de chorar, de sofrer com quem sofre. Existe espa\u00e7o pra dor no cristianismo e na nossa f\u00e9 pra tudo isso, pra cada momento da vida. E Deus segue sendo soberano, compassivo e acolhendo nossa dor e sofrimento em cada parte; Ele segue sofrendo com a gente.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Podemos ver em alguns Salmos: algu\u00e9m mal, numa<em> bad<\/em> profunda mesmo, desacreditado da vida e ainda assim com f\u00e9 e certeza de Deus ser o \u00fanico ref\u00fagio e sa\u00edda em momentos t\u00e3o cru\u00e9is. Em J\u00f3, mais uma pessoa depressiva, desejando literalmente morrer e nunca ter nascido. E em v\u00e1rios momentos dessa narrativa, pessoas com muito mais dor e sofrimento e vidas tr\u00e1gicas do que alegrias.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas sabemos tamb\u00e9m que no fim de tudo, mas s\u00f3 no fim mesmo, \u00e9 s\u00f3 a\u00ed que vamos ter o Shalom real oficial; s\u00f3 a\u00ed que a vida vai ser plena, que seremos completos e verdadeiramente felizes e que vai ficar tudo realmente bem. N\u00e3o \u00e9 agora, n\u00e3o \u00e9 nessa vida. Nosso verdadeiro e \u00fanico Messias precisa fazer aquela volta prometida aqui nesse mundo pra isso acontecer. Por enquanto, a gente luta e caminha um pouco mais todos os dias provando o sustento da gra\u00e7a e bondade de Deus e seu Esp\u00edrito Santo nos guiando e renovando nas que parecem m\u00ednimas, mas importantes tarefas do nosso cotidiano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, n\u00e3o se cobre e n\u00e3o espere a felicidade agora, afinal h\u00e1 tempo pra todas as coisas. Se voc\u00ea est\u00e1 bem e com seu emprego, seja o \u201cestar bem\u201d e o emprego de quem est\u00e1 sem nada agora. Se voc\u00ea est\u00e1 bem e psicologicamente com a cabe\u00e7a no lugar, seja essa cabe\u00e7a pra quem j\u00e1 n\u00e3o sabe mais o que fazer. Isso d\u00e1 muito mais significado &#8211; se n\u00e3o o verdadeiro &#8211; em ser o corpo de Cristo. N\u00e3o viva essa vida pra voc\u00ea, apenas, mas veja como ser a extens\u00e3o desse Reino que j\u00e1 est\u00e1 por aqui, mas que ainda vai vir por completo. E n\u00e3o fique bem se n\u00e3o estiver. Voc\u00ea tem espa\u00e7o pra isso em Cristo que \u00e9 o \u00fanico consolo e esperan\u00e7a.<\/span><\/p>\n<ul>\n<li><b>Gabriela Prillip<\/b>, 26 anos. \u00c9 marketeira, estudante de ci\u00eancias do consumo, tentando lidar com a vida adulta escrevendo. Congrega no Projeto 242.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Gabriela Prillip N\u00e3o \u00e9 um momento f\u00e1cil e a gente j\u00e1 cansou de trag\u00e9dia e tristeza pra saber disso, todo mundo fala isso o tempo todo. Eu j\u00e1 cansei de novo s\u00f3 de escrever aqui. A vida muitas vezes parece injusta e \u00e9; parece um sofrimento e caos sem fim e as vezes \u00e9 mesmo. [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6054],"tags":[5406,5544,40410,6048],"class_list":["post-8167","post","type-post","status-publish","format-standard","hentry","category-textos","tag-crise","tag-felicidade","tag-gabriela-prillip","tag-tempo"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/8167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=8167"}],"version-history":[{"count":2,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/8167\/revisions"}],"predecessor-version":[{"id":8170,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/8167\/revisions\/8170"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=8167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=8167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=8167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}