{"id":6527,"date":"2018-01-05T15:54:36","date_gmt":"2018-01-05T18:54:36","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/jovem\/?p=6527"},"modified":"2018-01-05T15:54:36","modified_gmt":"2018-01-05T18:54:36","slug":"corra-no-summer-camp-e-ajude-refugiados","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2018\/01\/05\/corra-no-summer-camp-e-ajude-refugiados\/","title":{"rendered":"Corra no Summer Camp e ajude refugiados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-6528\" src=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/Ult_Jovem_05_01_17_corrida-300x170.png\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/Ult_Jovem_05_01_17_corrida-300x170.png 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/Ult_Jovem_05_01_17_corrida.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O\u00a0<a href=\"http:\/\/tsbr.org.br\/congresso\/\">Summer Camp<\/a> \u00e9 um congresso do <a href=\"http:\/\/tsbr.org.br\/\">iTSBR<\/a>\u00a0(Instituto\u00a0TeenStreetBrasil) que acontece h\u00e1 14 anos em Maring\u00e1 (PR) e tem o objetivo de levar os adolescentes a uma vida de testemunho e intimidade verdadeira com Jesus durante suas f\u00e9rias de ver\u00e3o. Na hist\u00f3ria do evento, que re\u00fane mais de 2 mil participantes por edi\u00e7\u00e3o, 50 jovens j\u00e1 foram enviados como mission\u00e1rios.<\/p>\n<p>Durante o evento, que acontece em duas semanas, para grupos diferentes, primeiro de 15 a 20 de janeiro, depois de 23 a 28 do mesmo m\u00eas, \u00e9 realizada a TNT (Teens Need Teens), uma corrida empolgante e cheia de obst\u00e1culos que funciona como um meio de ajudar o pr\u00f3ximo, engajando os adolescentes presentes no congresso a se colocarem \u00e0 disposi\u00e7\u00e3o para ajudar outros adolescentes que passam por obst\u00e1culos muito maiores na vida.<\/p>\n<p>Os participantes arrecadam qualquer quantia em dinheiro, que serve como inscri\u00e7\u00e3o para essa esp\u00e9cie de corrida maluca, que \u00e9 exclusiva para os inscritos no evento. Toda verba arrecadada \u00e9 destinada para uma institui\u00e7\u00e3o que atende adolescentes e jovens. Projetos no Sert\u00e3o brasileiro, Irlanda, Nepal, Mal\u00e1sia, Uruguai e Haiti j\u00e1 foram beneficiados nas edi\u00e7\u00f5es anteriores.<!--more--><\/p>\n<p>Nesse ano quem receber\u00e1 toda a arrecada\u00e7\u00e3o da Corrida TNT \u00e9 a\u00a0<a href=\"https:\/\/www.facebook.com\/preparando.caminho.ong\/\">ONG Preparando o Caminho<\/a>, que trabalha com refugiados no Brasil. A miss\u00e3o da ONG \u00e9 levar informa\u00e7\u00e3o aos imigrantes sobre os servi\u00e7os b\u00e1sicos dispon\u00edveis em S\u00e3o Paulo, sejam eles oferecidos pelo estado ou outras ONG\u2019s, para contribuir para a forma\u00e7\u00e3o de uma sociedade mais inclusiva que respeite a diversidade cultural e combata a xenofobia, intoler\u00e2ncia, preconceito e discrimina\u00e7\u00e3o.<\/p>\n<p>Ficou com vontade de ajudar, mas n\u00e3o vai conseguir ir ao Summer Camp? N\u00e3o tem problema: qualquer pessoa pode contribuir, mesmo se n\u00e3o estiver participando diretamente do evento. \u00c9 s\u00f3 fazer a sua doa\u00e7\u00e3o pelo <a href=\"https:\/\/www.catarse.me\/tnt2018\">Catarse<\/a>! Ap\u00f3s a totaliza\u00e7\u00e3o das arrecada\u00e7\u00f5es, tanto pelo site quanto na Corrida TNT no congresso, o iTSBR postar\u00e1 informa\u00e7\u00f5es e v\u00eddeo mostrando a entrega da doa\u00e7\u00e3o, para todo mundo acompanhar de perto. Para mais informa\u00e7\u00f5es, entre em contato com o\u00a0<a href=\"https:\/\/www.facebook.com\/institutoteenstreetbrasil\/\">iTSBR<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00a0Summer Camp \u00e9 um congresso do iTSBR\u00a0(Instituto\u00a0TeenStreetBrasil) que acontece h\u00e1 14 anos em Maring\u00e1 (PR) e tem o objetivo de levar os adolescentes a uma vida de testemunho e intimidade verdadeira com Jesus durante suas f\u00e9rias de ver\u00e3o. Na hist\u00f3ria do evento, que re\u00fane mais de 2 mil participantes por edi\u00e7\u00e3o, 50 jovens j\u00e1 foram [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[31348,31349],"class_list":["post-6527","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-itsbr","tag-summer-camp"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/6527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=6527"}],"version-history":[{"count":2,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/6527\/revisions"}],"predecessor-version":[{"id":6530,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/6527\/revisions\/6530"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=6527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=6527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=6527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}