{"id":2785,"date":"2013-06-14T13:21:30","date_gmt":"2013-06-14T16:21:30","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/jovem\/?p=2785"},"modified":"2013-06-14T13:21:30","modified_gmt":"2013-06-14T16:21:30","slug":"vamos-mudar","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2013\/06\/14\/vamos-mudar\/","title":{"rendered":"Vamos mudar?"},"content":{"rendered":"<p><a href=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/06\/UltJovem_14_06_13_mala.jpg\" class=\"lightview\" data-lightview-group=\"group-2785\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-2786\" alt=\"UltJovem_14_06_13_mala\" src=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/06\/UltJovem_14_06_13_mala.jpg\" width=\"340\" height=\"250\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/06\/UltJovem_14_06_13_mala.jpg 340w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/06\/UltJovem_14_06_13_mala-300x220.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/06\/UltJovem_14_06_13_mala-150x110.jpg 150w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a>Conversas em redes sociais sempre rendem inspira\u00e7\u00f5es. Na verdade, rendem s\u00f3 se voc\u00ea cruzar com um amigo ou amiga que tem o que dizer. Ontem encontrei uma amiga gente boa e que sempre tem umas impress\u00f5es bem bacanas sobre os dilemas da vida.<\/p>\n<p>Mudan\u00e7a? Sim, isso mesmo, mudan\u00e7a. O papo come\u00e7ou com a seguinte declara\u00e7\u00e3o da minha amiga: \u201ccara, estou mudando de casa pelo nona vez em cinco anos. Quer fazer a conta?\u201d.<\/p>\n<p>A conversa durou mais um pouco, e, ao desconectar-me da internet, continuei refletindo sobre esse papo de mudar. Isso me fez lembrar que, seja qual for a mudan\u00e7a, ela sempre nos leva a mexer em caixas e revirar gavetas. Acabamos encontrando fotos antigas, rindo, chorando, lembrando e querendo esquecer.<!--more--><\/p>\n<p>Em nossa jornada, as mudan\u00e7as fazem parte desse card\u00e1pio de anos que passam cada vez mais velozmente.<\/p>\n<p>Mas o que ter\u00e1 de bom em mudar? Um novo corte de cabelo te deixa mais interessante? Uma roupa nova te coloca como algu\u00e9m que est\u00e1 por dentro da \u00faltima semana de moda de S\u00e3o Paulo? Ah mudan\u00e7a! Seria ela capaz de mexer com nosso interior? Teria ela o poder de abrir novas perspectivas? \u201cChega\u201d, voc\u00ea pode dizer, \u201cvoc\u00ea faz muitas perguntas, mas eu quero respostas\u201d.<\/p>\n<p>Vai mudar de casa e precisa fazer uma faxina antes de sair? N\u00e3o fa\u00e7a uma limpeza superficial. Aproveite para jogar fora um monte de coisas desnecess\u00e1rias para que coisas novas possam chegar. Mude o que for necess\u00e1rio, mas guarde bem guardado o que \u00e9 essencial. Voc\u00ea vai precisar disso em sua pr\u00f3xima mudan\u00e7a.<\/p>\n<p>_________<\/p>\n<p><strong><a href=\"jeverton.ledo@gmail.com\" target=\"_blank\">Jeverton \u201cMagr\u00e3o\u201d Ledo<\/a> \u00e9 mission\u00e1rio e capel\u00e3o escolar.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conversas em redes sociais sempre rendem inspira\u00e7\u00f5es. Na verdade, rendem s\u00f3 se voc\u00ea cruzar com um amigo ou amiga que tem o que dizer. Ontem encontrei uma amiga gente boa e que sempre tem umas impress\u00f5es bem bacanas sobre os dilemas da vida. Mudan\u00e7a? Sim, isso mesmo, mudan\u00e7a. O papo come\u00e7ou com a seguinte declara\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8039],"tags":[13876,13866,18316,164],"class_list":["post-2785","post","type-post","status-publish","format-standard","hentry","category-altas-devocionais","tag-altas-devocionais-2","tag-magrao","tag-mudanca","tag-vida-crista"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/2785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=2785"}],"version-history":[{"count":1,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/2785\/revisions"}],"predecessor-version":[{"id":2787,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/2785\/revisions\/2787"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=2785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=2785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=2785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}