{"id":2755,"date":"2013-04-29T09:33:28","date_gmt":"2013-04-29T12:33:28","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/jovem\/?p=2755"},"modified":"2013-04-29T09:44:48","modified_gmt":"2013-04-29T12:44:48","slug":"naufragos","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2013\/04\/29\/naufragos\/","title":{"rendered":"N\u00e1ufragos"},"content":{"rendered":"<p><em>Por Amanda Alves<\/em><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/04\/onda.jpg\" class=\"lightview\" data-lightview-group=\"group-2755\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2756\" alt=\"onda\" src=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/04\/onda.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/04\/onda.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2013\/04\/onda-150x99.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>No mar da vida o desejo de todo ser humano \u00e9 de sempre nadar em \u00e1guas tranquilas, pois \u00e1guas agitadas geram instabilidade e medo do desconhecido, afinal, quem \u00e9 que se sente confort\u00e1vel em meio a uma situa\u00e7\u00e3o na qual n\u00e3o se tem o controle?<\/p>\n<p>Sejamos francos, quantas vezes oramos a noite para que o Senhor nos direcione e nos ajude a encontrar uma solu\u00e7\u00e3o, mas no dia seguinte, levantamos cheios de planos, atalhos, jeitinhos&#8230;? A verdade \u00e9 que sempre encontramos uma forma de nos aventurarmos em mares distantes, \u00e0s vezes por curiosidade apenas, outras por ansiedade e vontade de achar um caminho mais pr\u00e1tico, ou ainda por teimosia, desobedi\u00eancia.<\/p>\n<p>Deus nos pro\u00edbe de nadar em determinadas \u00e1guas porque ele sabe que tal atitude implica em autodestrui\u00e7\u00e3o. N\u00e3o s\u00e3o poucas as vezes que julgamos ser experientes o bastante e ent\u00e3o sa\u00edmos por a\u00ed nadando nas nossas pr\u00f3prias escolhas. Tudo acontece de forma t\u00e3o sutil que, sem perceber, negligenciamos pouco a pouco a \u201cboia salva vidas\u201d, a palavra de Deus. Deixamos nos levar pelas fortes correntezas dos desejos, sonhos, projetos pessoais e convic\u00e7\u00f5es humanas.<\/p>\n<h5><span style=\"color: #0000ff;\">De repente, encontramo-nos como verdadeiros n\u00e1ufragos!<\/span><\/h5>\n<p><!--more--><\/p>\n<p>Cedo ou tarde as tempestades nos alcan\u00e7am e a sensa\u00e7\u00e3o \u00e9 que nossa vida vira de cabe\u00e7a para baixo, circunst\u00e2ncias adversas se levantam contra n\u00f3s e algumas certezas que possu\u00edamos s\u00e3o levadas pelo vento. Nessas horas j\u00e1 n\u00e3o sabemos como resolver ou o que fazer para cessar tamanha chuva.<\/p>\n<p>Quando sentimos que estamos naufragando, o p\u00e2nico toma conta do nosso ser, a nossa vis\u00e3o torna-se emba\u00e7ada, o frio insuport\u00e1vel penetra a nossa pele e nos tornamos incapacitados de enxergar a m\u00e3o do Senhor estendida em nossa dire\u00e7\u00e3o. \u00c9 por isso que, em alguns momentos, \u00e9 necess\u00e1rio que Deus permita que nos afoguemos para aprendermos a nos assegurar unicamente nele. Tal atitude faz parte do cuidado de um Pai para com os seus filhos.<\/p>\n<p>Est\u00e1 cansado de nadar pelas suas pr\u00f3prias for\u00e7as? Pare e Confie! O mar est\u00e1 violento? Olhe apenas para Cristo!<\/p>\n<p>Ao ler Mateus 14.25-32, percebemos que Pedro conseguiu dar algumas passadas sobre as \u00e1guas enquanto estava focado unicamente no Senhor Jesus, por\u00e9m, quando ele olhou para as circunst\u00e2ncias em sua volta, o temor dominou seu cora\u00e7\u00e3o e ent\u00e3o, como o texto muito bem apresenta, ele afundou. Quem nunca foi um Pedro nas tribula\u00e7\u00f5es da vida? Encontramo-nos t\u00e3o desesperados que s\u00f3 sabemos gritar: Salva-me! Mas a f\u00e9 verdadeira, onde est\u00e1?<\/p>\n<p>F\u00e9 \u00e9 uma palavra de uma s\u00edlaba s\u00f3, duas letras apenas, que firmadas naquele que subsisti para todo sempre reproduz consequ\u00eancias eternas. \u00c9 esta f\u00e9 que nos faz contemplar naquele imenso mar escuro e tempestuoso um farol reluzente que norteia a nosso caminho de volta, fazendo com que os perdidos sejam achados. Portanto, independente de como as nossas vidas encontram-se nesse momento \u00e9 para esta luz que devemos fitar os olhos, pois \u00e9 no nosso Senhor que encontramos seguran\u00e7a em meio \u00e0s crises, f\u00e9 para superarmos as barreiras do medo, esperan\u00e7a de que a chuva cesse, e certeza de que por traz das nuvens negras existe um sol que brilha.<\/p>\n<p>____________________<\/p>\n<p><strong>Amanda Alves<\/strong> tem 22 anos, mora em\u00a0Campina Grande, Para\u00edba. \u00c9 membro da Igreja Crist\u00e3 Nova Vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Amanda Alves No mar da vida o desejo de todo ser humano \u00e9 de sempre nadar em \u00e1guas tranquilas, pois \u00e1guas agitadas geram instabilidade e medo do desconhecido, afinal, quem \u00e9 que se sente confort\u00e1vel em meio a uma situa\u00e7\u00e3o na qual n\u00e3o se tem o controle? Sejamos francos, quantas vezes oramos a noite [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6054],"tags":[],"class_list":["post-2755","post","type-post","status-publish","format-standard","hentry","category-textos"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/2755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=2755"}],"version-history":[{"count":4,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/2755\/revisions"}],"predecessor-version":[{"id":2759,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/2755\/revisions\/2759"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=2755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=2755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=2755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}