{"id":1839,"date":"2012-07-07T10:23:23","date_gmt":"2012-07-07T13:23:23","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/jovem\/?p=1839"},"modified":"2012-07-07T10:25:05","modified_gmt":"2012-07-07T13:25:05","slug":"1839","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2012\/07\/07\/1839\/","title":{"rendered":"Vem a\u00ed: Temporada Kids e Teens"},"content":{"rendered":"<p><a href=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/07\/JV.jpeg\" class=\"lightview\" data-lightview-group=\"group-1839\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\" data-lightview-title=\"JV\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-1840\" title=\"JV\" src=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/07\/JV.jpeg\" alt=\"\" width=\"346\" height=\"230\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/07\/JV.jpeg 384w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/07\/JV-300x200.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/07\/JV-150x100.jpg 150w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><\/a>O Acampamento <a href=\"http:\/\/www.jovensdaverdade.com.br\/\" target=\"_blank\">Jovens da Verdade<\/a> oferece duas semanas de temporada nas\u00a0f\u00e9rias escolares de janeiro e julho. S\u00e3o semana para crian\u00e7as, de 7 a 11\u00a0anos, e outra para adolescentes de 12 a 20 anos, cujos objetivos: evangelizar,\u00a0edificar, recrear e discipular crian\u00e7as e adolescentes.<\/p>\n<p>\u201cViva La Vida \u2013 Eu vim para que tenham vida e a desfrutem eternamente. Jo\u00e3o\u00a010:10\u201d \u00e9 o tema da temporada desse m\u00eas de Julho. Na \u00faltima temporada tivemos\u00a0100 crian\u00e7as e 250 adolescentes, e a festa j\u00e1 est\u00e1 preparada para receber ainda mais\u00a0nesse m\u00eas.<\/p>\n<p>Se voc\u00ea tem um sobrinho, filho ou amigo entre 7 e 11 anos, a temporada Kids\u00a0ser\u00e1 entre os dias 8 a 14 de julho. J\u00e1 a temporada Teens nos dias 15 a 21. Corra\u00a0porque ainda h\u00e1 vagas!<\/p>\n<p>Confira mais detalhes da temporada e de outros eventos <a href=\"http:\/\/www.jovensdaverdade.com.br\/\" target=\"_blank\">p\u00e1gina do JV<\/a>.<\/p>\n<p>Os v\u00eddeos e fotos das temporada ser\u00e3o colocadas em tempo real na <a href=\"www.Facebook.com\/jovensdaverdade\" target=\"_blank\">p\u00e1gina do\u00a0Facebook <\/a>do JV2012.<\/p>\n<p>Um grande abra\u00e7o a todos e nos vemos l\u00e1 no acampamento<\/p>\n<p><em>Marcos Botelho<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Acampamento Jovens da Verdade oferece duas semanas de temporada nas\u00a0f\u00e9rias escolares de janeiro e julho. S\u00e3o semana para crian\u00e7as, de 7 a 11\u00a0anos, e outra para adolescentes de 12 a 20 anos, cujos objetivos: evangelizar,\u00a0edificar, recrear e discipular crian\u00e7as e adolescentes. \u201cViva La Vida \u2013 Eu vim para que tenham vida e a desfrutem [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[172],"tags":[],"class_list":["post-1839","post","type-post","status-publish","format-standard","hentry","category-agenda"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/1839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=1839"}],"version-history":[{"count":4,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/1839\/revisions"}],"predecessor-version":[{"id":1844,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/1839\/revisions\/1844"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=1839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=1839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=1839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}