{"id":1790,"date":"2012-06-25T09:04:29","date_gmt":"2012-06-25T12:04:29","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/jovem\/?p=1790"},"modified":"2012-06-26T09:16:12","modified_gmt":"2012-06-26T12:16:12","slug":"um-convite-ao-equilibrio","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/jovem\/2012\/06\/25\/um-convite-ao-equilibrio\/","title":{"rendered":"Um convite ao equil\u00edbrio"},"content":{"rendered":"<address><a href=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/06\/875807_equilibrio.jpg\" class=\"lightview\" data-lightview-group=\"group-1790\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\" data-lightview-title=\"875807_equilibrio\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-1791\" title=\"875807_equilibrio\" src=\"http:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/06\/875807_equilibrio.jpg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/06\/875807_equilibrio.jpg 300w, https:\/\/ultimato.com.br\/sites\/jovem\/files\/2012\/06\/875807_equilibrio-150x97.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/address>\n<address>Por Dani Nogueira<\/address>\n<address>\u00a0<\/address>\n<address>&#8220;Alegre-se, jovem, na sua mocidade! Seja feliz o seu cora\u00e7\u00e3o nos dias da sua juventude! Siga por onde seu cora\u00e7\u00e3o mandar, at\u00e9 onde a sua vista alcan\u00e7ar; mas saiba que por todas essas coisas Deus o trar\u00e1 a julgamento&#8221;. [Ec 11:9]<\/address>\n<address>\u00a0<\/address>\n<p>Esse vers\u00edculo, figurinha carimbada em mensagens para jovens, me fez repensar sobre seu real significado. N\u00e3o que o tenha interpretado errado antes, mas, ele me chamou a aten\u00e7\u00e3o para a conclus\u00e3o.<\/p>\n<p>Na vers\u00e3o em ingl\u00eas, com tradu\u00e7\u00e3o feita livremente por mim, ele diz mais ou menos o seguinte: \u201cvoc\u00eas que s\u00e3o jovens, fiquem felizes enquanto ainda s\u00e3o jovens, e deixe seu cora\u00e7\u00e3o dar a voc\u00eas alegrias em sua juventude. Siga os caminhos do seu cora\u00e7\u00e3o e qualquer coisa que seus olhos vejam, mas saibam que por todas essas coisas Deus vai trazer em julgamento sobre voc\u00eas\u201d.<\/p>\n<p><!--more--><\/p>\n<p>Da forma em que foi escrito em ingl\u00eas, esse vers\u00edculo se torna bem interessante. \u00c9 como se o autor estivesse dizendo: \u201cfa\u00e7am o que voc\u00eas estiverem a fim de fazer, curtam a vida adoidado&#8230; mas, lembre-se que Deus est\u00e1 vendo tudo o que fazem\u201d.<\/p>\n<p>Alguns pais t\u00eam essa t\u00e9cnica de educa\u00e7\u00e3o. \u201cFa\u00e7a o que quiser, mas eu n\u00e3o gostaria que voc\u00ea fizesse\u201d. Palavras que n\u00e3o vem do nosso cora\u00e7\u00e3o, mas que mostram um <em>convite ao equil\u00edbrio<\/em>, e, mais ainda, um dos ind\u00edcios da gra\u00e7a no Antigo Testamento. A gra\u00e7a nos d\u00e1 liberdade de fazermos o que quisermos, sem regras para conquistar a salva\u00e7\u00e3o ou agradar a Deus. E \u00e9 exatamente o que a gra\u00e7a faz que as pessoas entendem equivocadamente, na maioria das vezes.<\/p>\n<p>Posso parecer radical demais. Mas, falo dessa forma porque, de fato, muitas pessoas n\u00e3o entendem <em>gra\u00e7a<\/em>. Acham que \u00e9 desculpa para pecarmos desenfreadamente. Paulo j\u00e1 sofria com esse problema, como vemos em Romanos 6:1: \u201cQue diremos ent\u00e3o? Continuaremos pecando para que a gra\u00e7a aumente?\u201d. Ele mesmo responde a pergunta no vers\u00edculo seguinte: \u201cDe maneira nenhuma! N\u00f3s, os que morremos para o pecado, como podemos continuar vivendo nele?\u201d.<\/p>\n<p>N\u00e3o preciso dizer muita coisa ap\u00f3s essa objetiva e clara explica\u00e7\u00e3o de Paulo, mas, sinto-me no dever de voltar ao vers\u00edculo que ilustra o <em>post<\/em>. O que o autor de Eclesiastes disse foi o que Paulo disse, de outra forma. E ele entendia a natureza radical da juventude. Tendemos a ser extremos em tudo que fazemos. N\u00e3o conseguimos curtir a vida sem ser de forma adoidada. N\u00e3o conseguimos seguir regras sem nos tornarmos legalistas. Claro, como eu disse, isso \u00e9 uma tend\u00eancia natural da juventude.<\/p>\n<p>O convite ao equil\u00edbrio \u00e9 o convite da gra\u00e7a exatamente porque a gra\u00e7a nos convida a esse equil\u00edbrio. Pelo sacrif\u00edcio de Jesus somos livres para fazermos qualquer coisa, n\u00e3o estamos presos no pecado nem nas r\u00edgidas regras que o legalismo tenta nos impor. Mas lembremo-nos que a gra\u00e7a n\u00e3o \u00e9 de gra\u00e7a. O sacrif\u00edcio de Jesus jamais poder\u00e1 ser pago por nada que fa\u00e7amos. A \u00fanica forma que vejo de viver, depois de conhecer a gra\u00e7a, \u00e9 o equil\u00edbrio. \u00c9 me alegrar plenamente em Jesus\u00a0para que Ele seja mais glorificado, como diz o pr. americano John Piper. E \u00e9 viver em obedi\u00eancia porque reconhe\u00e7o a import\u00e2ncia do sacrif\u00edcio de Jesus na cruz por mim, pelos meus pecados.<\/p>\n<p>Obviamente, reconhe\u00e7o que n\u00e3o \u00e9 f\u00e1cil encontrar esse equil\u00edbrio. Demora at\u00e9 acharmos o centro gravitacional de algumas coisas. Mas \u00e9 preciso. \u00c9 a gra\u00e7a que nos capacita, n\u00e3o nossos pr\u00f3prios esfor\u00e7os. Isso n\u00e3o significa que devemos ficar inertes esperando o equil\u00edbrio, mas saber, em nossa busca, que n\u00e3o somos n\u00f3s que alcan\u00e7amos o equil\u00edbrio, mas Ele que nos ajuda a encontr\u00e1-lo.<\/p>\n<p>Viver sabendo que Deus trar\u00e1 julgamento sobre meus atos n\u00e3o deve ser motivo para viver assustado, mas sim de viver em gratid\u00e3o a Ele e aceitar o convite ao equil\u00edbrio que Ele nos enviou por gra\u00e7a.<\/p>\n<p>____________________<\/p>\n<p><strong><a href=\"http:\/\/www.facebook.com\/profile.php?id=539470900\" target=\"_blank\">Dani Nogueira<\/a><\/strong>, 23 anos, mora em Belo Horizonte (MG), \u00e9 fonoaudi\u00f3loga e escreve pro blog\u00a0<a href=\"http:\/\/www.trintaetresdc.blogspot.com\/\" target=\"_blank\">Trintaetr\u00eas<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Dani Nogueira \u00a0 &#8220;Alegre-se, jovem, na sua mocidade! Seja feliz o seu cora\u00e7\u00e3o nos dias da sua juventude! Siga por onde seu cora\u00e7\u00e3o mandar, at\u00e9 onde a sua vista alcan\u00e7ar; mas saiba que por todas essas coisas Deus o trar\u00e1 a julgamento&#8221;. [Ec 11:9] \u00a0 Esse vers\u00edculo, figurinha carimbada em mensagens para jovens, me [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1790","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/1790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/comments?post=1790"}],"version-history":[{"count":4,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/1790\/revisions"}],"predecessor-version":[{"id":1795,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/posts\/1790\/revisions\/1795"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/media?parent=1790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/categories?post=1790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/jovem\/wp-json\/wp\/v2\/tags?post=1790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}