{"id":742,"date":"2016-07-28T08:47:36","date_gmt":"2016-07-28T11:47:36","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/john-stott\/?p=742"},"modified":"2016-07-28T08:47:36","modified_gmt":"2016-07-28T11:47:36","slug":"sete-livros-de-stott-que-me-ensinaram-sobre-vida-crista-e-missao","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/john-stott\/2016\/07\/28\/sete-livros-de-stott-que-me-ensinaram-sobre-vida-crista-e-missao\/","title":{"rendered":"Sete livros de Stott que me ensinaram sobre vida crist\u00e3 e miss\u00e3o"},"content":{"rendered":"<p><span style=\"color: #993300;\"><em>Por H\u00e9ber Negr\u00e3o<\/em><\/span><\/p>\n<p>Em sua \u00faltima carta Paulo exorta Tim\u00f3teo a compartilhar o que ele havia aprendido com Paulo, passando este ensino a fi\u00e9is testemunhas (2 Tm 2.2). Mantendo as devidas propor\u00e7\u00f5es, posso dizer que este \u00e9 o meu desejo com este texto. Quero mostrar o que tenho aprendido com as acuradas reflex\u00f5es que John Stott tem feito da B\u00edblia, do Cristianismo e da <em>Missio Dei<\/em>. Eu j\u00e1 tinha conhecimento de quem era John Stott e o que ele representava no movimento crist\u00e3o, por\u00e9m nada substitui o contato com a obra do autor. O primeiro livro de sua autoria que eu li foi h\u00e1 10 anos e desde ent\u00e3o este homem de Deus tem marcado minha caminhada na vida crist\u00e3 e no minist\u00e9rio.<\/p>\n<p>Este texto \u00e9 tamb\u00e9m um exerc\u00edcio para a minha mente e alma. Antes de escrev\u00ea-lo, eu decidi fazer uma lista mental de cada livro dele que li nos \u00faltimos anos e puxando apenas pela mem\u00f3ria selecionei pelo menos um ensinamento que me marcou em cada livro, associando-o com a \u00e9poca de vida em que eu me encontrava durante aquela leitura. Com exce\u00e7\u00e3o das duas \u00faltimas obras, voltei-me aos referidos livros apenas para procurar as cita\u00e7\u00f5es adequadas para cada t\u00f3pico.\u00a0Precisamos de exerc\u00edcios como este de vez em quando. Confira a seguir o livro, o ano em que eu o li e as li\u00e7\u00f5es que aprendi.<\/p>\n<p>***<strong><br \/>\n<\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/por-que-sou-cristao\"><br \/>\nPorque Sou Crist\u00e3o<\/a> &#8211; 2006<\/strong><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/capa_porquesoucristao-e1469704351160.jpg\" class=\"lightview\" data-lightview-group=\"group-742\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-743\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/capa_porquesoucristao-e1469704351160.jpg\" alt=\"Capa_Pq_Sou_Cristao_corel\" width=\"180\" height=\"257\" \/><\/a>H\u00e1 dez anos tive meu primeiro contato com um livro de John Stott. Ganhei este exemplar da minha irm\u00e3 quando me mudei para Belo Horizonte (MG) para fazer meu mestrado. Foi um ano de mudan\u00e7as dr\u00e1sticas na minha vida, n\u00e3o apenas porque eu estava saindo de casa, mas tamb\u00e9m porque eu estava me embrenhando nas profundas reflex\u00f5es acad\u00eamicas da universidade. O que me chamou muito a aten\u00e7\u00e3o neste livro foi a maneira como Stott retratou Jesus: &#8220;O C\u00e3o de Ca\u00e7a do C\u00e9u&#8221; logo no primeiro cap\u00edtulo. Que impacto! Para quem nunca havia lido John Stott voc\u00ea pode imaginar meu espanto com esta \u201cfalta de respeito\u201d. Mas que deleite foi o meu quando entendi que o<\/p>\n<blockquote><p>pr\u00f3prio Jesus Cristo, que me perseguiu\u00a0incansavelmente, mesmo quando eu estava correndo dele a fim de seguir meu pr\u00f3prio caminho. Se n\u00e3o fosse pela persegui\u00e7\u00e3o graciosa do C\u00e3o de Ca\u00e7a do C\u00e9u, hoje eu estaria na lata de lixo das vidas desperdi\u00e7adas e descartadas. (p 17)<\/p>\n<p>Se nos tornamos cientes da incans\u00e1vel busca de Cristo, desistirmos de tentar escapar dele e nos entregarmos ao abra\u00e7o desse &#8216;amante tremendo&#8217;, n\u00e3o haver\u00e1 espa\u00e7o para ostenta\u00e7\u00e3o em rela\u00e7\u00e3o \u00e0quilo que fazemos, mas somente uma profunda a\u00e7\u00e3o de gra\u00e7as por sua gra\u00e7a e miseric\u00f3rdia, e para a firme resolu\u00e7\u00e3o de passar o tempo e a eternidade ao seu servi\u00e7o (p 33)<\/p><\/blockquote>\n<p><strong><a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/cristianismo-basico\"><br \/>\n<\/a><a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/cristianismo-basico\">Cristianismo B\u00e1sico<\/a> &#8211; 2007<\/strong><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Cristianismo_Basico_Capa-e1469704451178.jpg\" class=\"lightview\" data-lightview-group=\"group-742\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-744\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Cristianismo_Basico_Capa-e1469704451178.jpg\" alt=\"capa02B\" width=\"180\" height=\"258\" \/><\/a>J\u00e1 no meu segundo ano do mestrado, morando em Belo Horizonte, participei do 1\u00ba F\u00f3rum Jovem de Miss\u00e3o Integral onde adquiri alguns livros da Editora Ultimato, entre eles <a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/cristianismo-basico\">Cristianismo B\u00e1sico<\/a>. Este foi pra mim um excelente renovo e refor\u00e7o da minha f\u00e9 crist\u00e3. Esse livro trata de assuntos elementares do cristianismo. Como garoto criado na igreja, eu tinha conhecimento da maioria deles, mas Stott, que ensina magistralmente, me levou a entender com mais clareza a profundidade do sacrif\u00edcio de Cristo.<\/p>\n<p>Me chocou entender que Cristo foi considerado maldito de Deus (n\u00e3o s\u00f3 por causa do nosso pecado, mas \u00a0tamb\u00e9m por causa da maldi\u00e7\u00e3o hist\u00f3rica de quem era pendurado no madeiro). Qual n\u00e3o foi a minha alegria quando eu entendi o cerne da \u00a0doutrina da justifica\u00e7\u00e3o, de que agora eu n\u00e3o era mais maldito, mas considerado justo porque Cristo se fez maldi\u00e7\u00e3o em meu lugar.<\/p>\n<blockquote><p>O Filho de Deus identificou-se com os pecados dos homens. Ele n\u00e3o se contentou em assumir a nossa natureza; tamb\u00e9m levou sobre si a nossa iniquidade. Ele n\u00e3o apenas \u2018se fez carne\u2019 no \u00fatero de Maria; ele \u2018se fez pecado\u2019 na cruz do calv\u00e1rio. (p 124)<\/p>\n<p>O fato de Jesus ter morrido pendurado \u2018sobre o madeiro\u2019 queria dizer que ele estava sob a maldi\u00e7\u00e3o divina (&#8230;). A maldi\u00e7\u00e3o que deveria cair sobre os pecadores por transgredirem a lei foi lan\u00e7ada sobre Jesus na cruz. Ele nos libertou da maldi\u00e7\u00e3o, tomando-a sobre si quando morreu (p 127,128)<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>Eu Creio na Prega\u00e7\u00e3o &#8211; 2009<\/strong><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Eu_Creio_Pregacao_Capa3d-e1469704759147.jpg\" class=\"lightview\" data-lightview-group=\"group-742\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-747\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Eu_Creio_Pregacao_Capa3d-e1469704759147.jpg\" alt=\"JS_28_07_16_Eu_Creio_Pregacao_Capa3d\" width=\"180\" height=\"280\" \/><\/a>Qual pregador nunca se viu no dilema de ter que pregar duramente contra pecados que ele mesmo comete? Justamente pelo fato de nenhum pregador ser homem perfeito esse dilema ocorre com frequ\u00eancia seja no gabinete seja no p\u00falpito. Passei por crise semelhante quando estava em meu segundo ano de semin\u00e1rio. Nosso professor de homil\u00e9tica nos deu uma lista de livros para lermos e fazermos uma resenha. Eu me voltei para John Stott e li \u201cEu Creio na Prega\u00e7\u00e3o\u201d. O pr\u00f3ximo par\u00e1grafo eu retirei da resenha que entreguei ao meu professor naquela ocasi\u00e3o.<\/p>\n<p>\u201cIniciei a leitura na sexta pela manh\u00e3 e no domingo \u00e0 noite eu pregaria na congrega\u00e7\u00e3o da Igreja Batista Si\u00e3o. Quanto mais eu me debru\u00e7ava na leitura menos eu me percebia capaz de assumir o p\u00falpito poucos dias depois. Como poderia eu, cheio de pecado, fraquezas e limita\u00e7\u00f5es, desempenhar uma fun\u00e7\u00e3o t\u00e3o importante quanto \u00e0 prega\u00e7\u00e3o da Palavra? Essa pergunta n\u00e3o me sa\u00eda da mente por um bom tempo durante minha leitura. O padr\u00e3o para o pregador era muito elevado. Eu jamais estaria \u00e0 altura de tal fun\u00e7\u00e3o. Com toda essa luta em mente, me deparei com a seguinte cita\u00e7\u00e3o:<\/p>\n<blockquote><p>Certamente devemos reconhecer a verdade de que somos seres humanos com nossas fraquezas e nossa condi\u00e7\u00e3o ca\u00edda, vulner\u00e1veis \u00e0 tenta\u00e7\u00e3o e ao sofrimento, lutando com as nossas d\u00favidas, com o medo e o pecado, necessitados continuamente da gra\u00e7a de Deus que perdoa e liberta. Dessa maneira o pregador pode continuar a ser exemplo \u2013 mas exemplo de humildade e verdade (p 284).<\/p><\/blockquote>\n<p>Isso veio como uma bomba de conforto ao meu cora\u00e7\u00e3o, uma verdadeira explos\u00e3o de suspiros aliviados. Eu n\u00e3o precisava ser um super-her\u00f3i que nunca errou para falar a um povo errante, eu n\u00e3o precisava ser algu\u00e9m que estava acima da congrega\u00e7\u00e3o por ter mais conhecimento da Palavra. Fechei o livro e orei pedindo miseric\u00f3rdia a Deus para que Ele me usasse naquela noite, apesar de mim.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A Cruz de Cristo &#8211; 2010<\/strong><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Cruz_Cristo_Capa3d-e1469704614339.jpg\" class=\"lightview\" data-lightview-group=\"group-742\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-746\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Cruz_Cristo_Capa3d-e1469704614339.jpg\" alt=\"JS_28_07_16_Cruz_Cristo_Capa3d\" width=\"180\" height=\"260\" \/><\/a>No \u00faltimo ano do semin\u00e1rio consegui um tempo nas f\u00e9rias para ler o que muitos consideram a obra prima de John Sott: o livro \u201cA Cruz de Cristo\u201d.\u00a0 Quantos ensinamentos incr\u00edveis eu achei neste livro, estranhei que ele n\u00e3o foi pedido como leitura obrigat\u00f3ria na disciplina de Teologia Sistem\u00e1tica. A grande vantagem de ler nas f\u00e9rias era que eu podia desfrutar da leitura com calma e sem a pressa habitual para cumprir prazos de leitura e entrega de resenha que os professores pediam.<\/p>\n<p>Dentre todas as coisas, o que me chamou a aten\u00e7\u00e3o neste livro foi a maneira como John Stott tratou sobre a cruz como um s\u00edmbolo de morte e o quanto este s\u00edmbolo \u201cmacabro\u201d representa vida para os crist\u00e3os. Ningu\u00e9m gosta de ter sua identidade associada a uma forca, guilhotina ou rev\u00f3lver, com exce\u00e7\u00e3o de n\u00f3s, crist\u00e3os:<\/p>\n<blockquote><p>Todas as religi\u00f5es e ideologias t\u00eam seu s\u00edmbolo visual, que exemplifica um aspecto importante de sua hist\u00f3ria ou cren\u00e7as (p. 13).<\/p>\n<p>Os crist\u00e3os poderiam ter escolhido a manjedoura em que o menino Jesus foi colocado, ou o banco de carpinteiro em que ele trabalhou (&#8230;) ou a toalha que ele usou para lavar os p\u00e9s dos disc\u00edpulos (&#8230;). Outras possibilidades eram o trono, s\u00edmbolo de soberania divina, ou a pomba, s\u00edmbolo do Esp\u00edrito Santo enviado do c\u00e9u no Pentecostes. Qualquer desde s\u00edmbolos teria sido apropriado para indicar um aspecto do minist\u00e9rio do Senhor. Mas pelo contr\u00e1rio, o s\u00edmbolo escolhido foi uma simples cruz. (&#8230;) [Os Crist\u00e3os] desejavam comemorar, como centro da compreens\u00e3o que tinham de Jesus, n\u00e3o o seu nascimento nem a sua juventude, nem seu ensino nem o seu servi\u00e7o, mas a sua morte e sua crucifica\u00e7\u00e3o (p. 14,15)<\/p><\/blockquote>\n<p><strong><a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/a-missao-crista-no-mundo-moderno\"><br \/>\nA Miss\u00e3o Crist\u00e3 no Mundo Moderno<\/a> &#8211; 2011<\/strong><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Missao_crista_3D-e1469704483697.jpg\" class=\"lightview\" data-lightview-group=\"group-742\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-745\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/07\/JS_28_07_16_Missao_crista_3D-e1469704483697.jpg\" alt=\"JS_28_07_16_Missao_crista_3D\" width=\"180\" height=\"289\" \/><\/a>Depois de me formar no semin\u00e1rio ingressei com minha esposa ao minist\u00e9rio. E logo em nosso primeiro ano de trabalho mission\u00e1rio de tempo integral tive contato com este livro que \u00e9 um excelente resumo da teologia de miss\u00e3o defendida por John Stott e herdada pelo Movimento Lausanne. Ler <a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/a-missao-crista-no-mundo-moderno\">A Miss\u00e3o Crist\u00e3 no Mundo Moderno<\/a> foi um marco para mim porque n\u00e3o s\u00f3 corroborou, mas intensificou a minha vis\u00e3o sobre a integralidade da miss\u00e3o da igreja e sobre a nossa participa\u00e7\u00e3o enquanto crist\u00e3os na Miss\u00e3o de Deus.<\/p>\n<p>A discurso de John Stott no 1\u00ba Congresso Internacional para Evangeliza\u00e7\u00e3o Mundial realizado em Lausanne ecoa nas p\u00e1ginas deste livro. O <a href=\"http:\/\/www.ultimato.com.br\/quem-somos#extras\">Pacto de Lausanne<\/a>, elaborado ao final daquele evento, e que hoje \u00e9 a base para muitas organiza\u00e7\u00f5es mission\u00e1rias no mundo inteiro, est\u00e1 exposto neste livro de maneira fluida.<\/p>\n<p>Aprendi em <a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/a-missao-crista-no-mundo-moderno\">A Miss\u00e3o Crist\u00e3 no Mundo Moderno<\/a> que a miss\u00e3o da igreja \u00e9 um reflexo da miss\u00e3o do Filho. Com esta leitura, Stott me chamou aten\u00e7\u00e3o para a t\u00e3o ignorada Grande Comiss\u00e3o do evangelho de Jo\u00e3o: servir como Jesus serviu.<\/p>\n<blockquote><p>A forma crucial como a Grande Comiss\u00e3o foi entregue a n\u00f3s (&#8230;), \u00e9 a joanina. [Em Jo 17.18 e 20.21] Jesus fez mais do que tra\u00e7ar um paralelo vago entre a sua miss\u00e3o e a nossa. Precisa e deliberadamente, ele fez de sua miss\u00e3o um modelo para a nossa dizendo: &#8216;assim como o Pai me enviou, eu tamb\u00e9m vos envio&#8217;. Portanto nossa compreens\u00e3o da miss\u00e3o da igreja deve ser deduzida da nossa compreens\u00e3o da miss\u00e3o do Filho. Por que e como o Pai enviou o Filho? (&#8230;) \u00c9 melhor come\u00e7ar com algo mais geral e dizer que ele veio para servir (p 27)<\/p><\/blockquote>\n<p><strong><a href=\"http:\/\/ultimato.com.br\/sites\/discipulo-radical\/\"><br \/>\n<\/a><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/02\/discipulo_radical.jpg\" class=\"lightview\" data-lightview-group=\"group-742\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-586\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/02\/discipulo_radical.jpg\" alt=\"discipulo_radical\" width=\"180\" height=\"270\" srcset=\"https:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/02\/discipulo_radical.jpg 180w, https:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/02\/discipulo_radical-100x150.jpg 100w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a><a href=\"http:\/\/ultimato.com.br\/sites\/discipulo-radical\/\">O Disc\u00edpulo Radical<\/a> &#8211; 2011<\/strong><\/p>\n<p>No final do ano de 2011 minha esposa e eu fomos a Londres participar de um treinamento para o nosso minist\u00e9rio. John Stott havia acabado de falecer e eu resolvi levar seu \u00faltimo livro para ler durante a viagem, em terras brit\u00e2nicas. Antes de retornarmos ao Brasil participamos do culto na <em>All Souls Church<\/em>, igreja onde John Stott pastoreou por muitos anos.<\/p>\n<p>Visitamos a igreja no domingo de 11 de setembro, exatamente 10 anos depois do atentado terrorista \u00e0s Torres G\u00eameas nos Estados Unidos. Um momento da liturgia que mais chamou a minha aten\u00e7\u00e3o foi a ora\u00e7\u00e3o pelo perd\u00e3o dos pecados. A ora\u00e7\u00e3o congregacional foi lida do come\u00e7o ao fim (algo interessante para se experimentar pelo menos uma vez na vida), e o assunto abordado foi tanto uma intercess\u00e3o pelas fam\u00edlias das v\u00edtimas quanto um pedido de perd\u00e3o pela omiss\u00e3o da igreja em fazer a diferen\u00e7a no mundo. Essa ora\u00e7\u00e3o me lembrou um documento que Stott citou em seu livro <a href=\"http:\/\/ultimato.com.br\/sites\/discipulo-radical\/\">O Disc\u00edpulo Radical<\/a>:<\/p>\n<blockquote><p>A igreja, juntamente com o resto da sociedade, est\u00e1 inevitavelmente envolvida na pol\u00edtica que \u00e9 &#8216;a arte de viver em comunidade&#8217;. Os servos de Cristo precisam expressar o senhorio dele em seus compromissos pol\u00edticos, econ\u00f4micos e sociais, e em seu amor por seu pr\u00f3ximo, participando do processo pol\u00edtico. Como ent\u00e3o podemos contribuir para a mudan\u00e7a?<\/p>\n<p>Em primeiro lugar, oraremos pela paz e pela justi\u00e7a, como Deus ordena. Em segundo lugar, procuraremos educar o povo crist\u00e3o nas quest\u00f5es morais e pol\u00edticas envolvidas (&#8230;). Em terceiro lugar, agiremos. (&#8230;) Todos os crist\u00e3os devem participar ativamente do esfor\u00e7o pela cria\u00e7\u00e3o de uma sociedade justa e respons\u00e1vel. (&#8230;) Como seguidores de Jesus, o Servo Sofredor, sabemos que o servi\u00e7o sempre envolve sofrimento (p 67)<\/p><\/blockquote>\n<p><strong><a href=\"http:\/\/ultimato.com.br\/sites\/crer-tambem-pensar\/\"><br \/>\n<\/a><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/06\/JS_26_07_16_Crer_Pensar_3D-e1469704248688.jpg\" class=\"lightview\" data-lightview-group=\"group-742\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-733\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/2016\/06\/JS_26_07_16_Crer_Pensar_3D-e1469704248688.jpg\" alt=\"JS_26_07_16_Crer_Pensar_3D\" width=\"180\" height=\"259\" \/><\/a><a href=\"http:\/\/ultimato.com.br\/sites\/crer-tambem-pensar\/\">Crer \u00e9 Tamb\u00e9m Pensar<\/a> &#8211; 2012<\/strong><\/p>\n<p>Em meu segundo ano de minist\u00e9rio tive a oportunidade de lecionar a disciplina de \u201cIntrodu\u00e7\u00e3o do Novo Testamento\u201d no semin\u00e1rio onde eu havia me formado dois anos antes.<\/p>\n<p>Sem lecionar por muito tempo, desde que terminei minha faculdade de Licenciatura em M\u00fasica, eu reavivei minha paix\u00e3o pelo ensino durante aqueles meses. Algo que sempre foi meu alvo enquanto professor em sala e enquanto pregador no p\u00falpito era que meu ensino fosse o mais compreens\u00edvel e o mais relevante poss\u00edvel para a minha audi\u00eancia.<\/p>\n<p>Tive o conforto ao ler <a href=\"http:\/\/ultimato.com.br\/sites\/crer-tambem-pensar\/\">Crer \u00e9 Tamb\u00e9m Pensar<\/a>, pois nele John Stott mostra que o homem foi criado \u00e0 imagem e semelhan\u00e7a de Deus e com capacidade para pensar. N\u00e3o devemos ter medo de refletir sobre assuntos controversos, precisamos abord\u00e1-los com a mente crist\u00e3. Stott tamb\u00e9m mostra algumas evid\u00eancias no Novo Testamento de que a comunica\u00e7\u00e3o do Evangelho deve ser feita de maneira acess\u00edvel e intelig\u00edvel. Ler isso renovou meu desejo de anunciar o evangelho contextualizado e relevante para meu p\u00fablico-alvo.<\/p>\n<blockquote><p>O argumento do ap\u00f3stolo diz que deve existir um conte\u00fado s\u00f3lido em nossa proclama\u00e7\u00e3o evangel\u00edstica de Jesus. \u00c9 nossa responsabilidade compartilhar Jesus Cristo na plenitude de sua pessoa divina-humana e de sua obra de salva\u00e7\u00e3o, para que essa &#8216;prega\u00e7\u00e3o sobre Cristo&#8217; possa gerar f\u00e9 no ouvinte.<\/p>\n<p>Paulo estava ensinando um conjunto de doutrinas e argumentando para chegar a uma conclus\u00e3o. Ele estava buscando convencer e n\u00e3o converter. (p 61)<\/p>\n<p>Tornar-se um crist\u00e3o \u00e9 &#8216;crer na verdade&#8217;, &#8216;obedecer \u00e0 verdade&#8217;, &#8216;reconhecer a verdade&#8217;. (&#8230;) O evangelho \u00e9 para todos, independentemente da educa\u00e7\u00e3o ou da falta dela. E o tipo de evangelismo que estou defendendo, que proclama Cristo em sua plenitude, \u00e9 relevante para todos os tipos de pessoas: crian\u00e7as e adultos, cultos e incultos, abor\u00edgenes australianos e intelectuais ocidentais. Pois a apresenta\u00e7\u00e3o desse evangelho n\u00e3o \u00e9 acad\u00eamica, mas racional (p \u00a063,64)<\/p><\/blockquote>\n<p>No exerc\u00edcio de mem\u00f3ria que foi produzir este texto lembrei-me ainda de duas coisas. A primeira delas \u00e9 que John Stott faleceu quatro dias depois de Amy Winehouse, cantora brit\u00e2nica que morreu de overdose com apenas 27 anos. Como era de se esperar, a m\u00eddia n\u00e3o noticiou a perda do te\u00f3logo de 90 anos, mas sem d\u00favida suas obras e sua vida ecoar\u00e3o por muito mais tempo e causar\u00e3o muito mais impacto do que os feitos da cantora.<\/p>\n<p>A segunda coisa que percebi \u00e9 que desde 2012 eu n\u00e3o leio um livro de John Stott. J\u00e1 est\u00e1 mais do que na hora de voltar a aprender com o \u201cTio John\u201d. Ent\u00e3o me d\u00e1 licen\u00e7a que eu tenho que d\u00e1 um pulinho ali na minha estante.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/twitter.com\/HeberNegrao\"><strong>\u2022 H\u00e9ber Negr\u00e3o <\/strong><\/a>\u00e9 paraense, tem 34 anos, mestre em Etnomusicologia e casado com Sophia. Ambos s\u00e3o mission\u00e1rios da\u00a0<a href=\"http:\/\/meib.com.br\/\">Miss\u00e3o Evang\u00e9lica aos \u00cdndios do Brasil (MEIB)<\/a> e da\u00a0<a href=\"http:\/\/www.missaoalem.org.br\/\">Associa\u00e7\u00e3o Lingu\u00edstica Evang\u00e9lica Mission\u00e1ria (ALEM)<\/a>. Residem em Paragominas (PA) e trabalham com o povo Temb\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por H\u00e9ber Negr\u00e3o Em sua \u00faltima carta Paulo exorta Tim\u00f3teo a compartilhar o que ele havia aprendido com Paulo, passando este ensino a fi\u00e9is testemunhas (2 Tm 2.2). Mantendo as devidas propor\u00e7\u00f5es, posso dizer que este \u00e9 o meu desejo com este texto. Quero mostrar o que tenho aprendido com as acuradas reflex\u00f5es que John [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[14830],"tags":[14830],"class_list":["post-742","post","type-post","status-publish","format-standard","hentry","category-meus-livros","tag-meus-livros"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/comments?post=742"}],"version-history":[{"count":1,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/742\/revisions"}],"predecessor-version":[{"id":748,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/742\/revisions\/748"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/media?parent=742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/categories?post=742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/tags?post=742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}