{"id":1229,"date":"2018-03-20T09:04:04","date_gmt":"2018-03-20T12:04:04","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/john-stott\/?p=1229"},"modified":"2018-04-25T08:33:44","modified_gmt":"2018-04-25T11:33:44","slug":"o-apelo-a-santidade","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/john-stott\/2018\/03\/20\/o-apelo-a-santidade\/","title":{"rendered":"O apelo \u00e0 santidade"},"content":{"rendered":"<blockquote><p>No m\u00eas de mar\u00e7o, a Editora Ultimato\u00a0comemorou\u00a0junto com a Alian\u00e7a B\u00edblica Universit\u00e1ria (ABU)\u00a0os\u00a043 anos de\u00a0<a href=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/2016\/03\/28\/em-1975-nascia-uma-editora-e-dai\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/ultimato.com.br\/sites\/blogdaultimato\/2016\/03\/28\/em-1975-nascia-uma-editora-e-dai\/&amp;source=gmail&amp;ust=1524138533689000&amp;usg=AFQjCNHyWO2HJpB6SSwBmIXUxmFBGXuKvw\">funda\u00e7\u00e3o da ABU Editora\u00a0<\/a>e\u00a0os\u00a07 anos de parceria,\u00a0desde\u00a0que Ultimato passou a ser a respons\u00e1vel por comercializar os livros dessa editora. Atualmente Ultimato tem mais de 50 t\u00edtulos da ABU em seu\u00a0<a href=\"http:\/\/ultimato.com.br\/loja\/catalogo\/editora\/abu\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/ultimato.com.br\/loja\/catalogo\/editora\/abu&amp;source=gmail&amp;ust=1524138533689000&amp;usg=AFQjCNGB3B9dGO3ctmrrC1Ep9FCD920iBA\">cat\u00e1logo<\/a>.<br \/>\n&nbsp;<br \/>\n<span style=\"font-weight: 400;\">A seguir voc\u00ea pode ler um trecho de <\/span><a href=\"http:\/\/ultimato.com.br\/sites\/john-stott\/2012\/08\/02\/crer-e-tambem-pensar\/\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">Crer \u00e9 Tamb\u00e9m Pensar<\/span><\/i><\/a><span style=\"font-weight: 400;\">, de John Stott, um cl\u00e1ssico da ABU Editora e um dos <a href=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/2018\/01\/03\/os-livros-mais-vendidos-em-2017\/\" target=\"_blank\" rel=\"noopener\">livros mais vendidos em 2017<\/a><\/span><span style=\"font-weight: 400;\">.<\/span><\/p><\/blockquote>\n<h4><strong>O apelo \u00e0 santidade<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-1235 size-medium\" title=\"Foto: Aziz Acharki | unsplash.com\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_Stott_Apelo_santidade_20_3_2018-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_Stott_Apelo_santidade_20_3_2018-300x200.jpg 300w, https:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_Stott_Apelo_santidade_20_3_2018-768x512.jpg 768w, https:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_Stott_Apelo_santidade_20_3_2018-732x488.jpg 732w, https:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_Stott_Apelo_santidade_20_3_2018.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Muitos segredos para a santidade nos s\u00e3o dados nas p\u00e1ginas da B\u00edblia. De fato, um dos maiores prop\u00f3sitos da B\u00edblia \u00e9 mostrar ao povo de Deus como viver de forma digna e agrad\u00e1vel ao Senhor. Por\u00e9m, um dos aspectos mais negligenciados na quest\u00e3o da santidade \u00e9 o papel da mente, mesmo que Jesus tenha esclarecido a quest\u00e3o quando prometeu que \u201cconhecer\u00e3o a verdade, e a verdade os libertar\u00e1\u201d.<\/span><span style=\"font-weight: 400;\">1<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 por meio da verdade que Cristo nos liberta do dom\u00ednio do pecado. Como isso funciona? Onde est\u00e1 o poder libertador da verdade?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para come\u00e7ar, precisamos ter uma vis\u00e3o clara do tipo de pessoa que Deus quer que sejamos. Precisamos conhecer as leis morais e os mandamentos de Deus. Como John Owen expressa, \u201caquele bem que a mente n\u00e3o pode descobrir, que a vontade n\u00e3o pode escolher, que os sentimentos n\u00e3o podem discernir\u201d. Ainda assim, \u201cnas Escrituras a corrup\u00e7\u00e3o da mente \u00e9 comumente vista como o princ\u00edpio de todo o pecado\u201d.<\/span><span style=\"font-weight: 400;\">2<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O melhor exemplo disso talvez seja encontrado no come\u00e7o da vida de nosso Salvador. Por tr\u00eas vezes o diabo veio at\u00e9 ele e o tentou no deserto da Judeia. Por tr\u00eas vezes ele reconheceu que a sugest\u00e3o do diabo era maligna e contr\u00e1ria \u00e0 vontade de Deus. Por tr\u00eas vezes ele enfrentou a tenta\u00e7\u00e3o com a palavra <\/span><i><span style=\"font-weight: 400;\">gegraptai<\/span><\/i><span style=\"font-weight: 400;\">, \u201cest\u00e1 escrito\u201d. N\u00e3o havia espa\u00e7o para debate ou argumento. O problema estava resolvido na mente dele desde o come\u00e7o. Porque a Escritura tinha estabelecido o que era certo. Um conhecimento claro da vontade de Deus \u00e9 o primeiro segredo para uma vida reta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, n\u00e3o \u00e9 suficiente sabermos o que devemos ser. Precisamos ir al\u00e9m e empenhar nossas mentes nisso. A batalha \u00e9 quase sempre ganha na mente. \u00c9 por meio da renova\u00e7\u00e3o da nossa mente que nosso car\u00e1ter e comportamento s\u00e3o transformados.<\/span><span style=\"font-weight: 400;\">3<\/span><span style=\"font-weight: 400;\"> Assim, as Escrituras nos chamam novamente para uma disciplina mental a esse respeito. \u201cTudo o que for verdadeiro\u201d \u2013 ela afirma \u2013 \u201ctudo o que for nobre, tudo o que for correto, tudo o que for puro, tudo o que for am\u00e1vel, tudo o que for de boa fama, se houver algo excelente ou digno de louvor, pensem nessas coisas\u201d.<\/span><span style=\"font-weight: 400;\">4<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Novamente, \u201cportanto, se voc\u00eas ressuscitaram com Cristo, procurem as coisas que s\u00e3o do alto, onde Cristo est\u00e1 assentado \u00e0 direita de Deus. Mantenham o pensamento nas coisas do alto, e n\u00e3o nas coisas terrenas. Pois voc\u00eas morreram, e agora a sua vida est\u00e1 escondida com Cristo em Deus\u201d.<\/span><span style=\"font-weight: 400;\">5<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E, uma vez mais, \u201cquem vive segundo a carne tem a mente voltada para o que a carne deseja; mas, quem vive de acordo com o Esp\u00edrito, tem a mente voltada para o que o Esp\u00edrito deseja. A mentalidade da carne \u00e9 morte, mas a mentalidade do Esp\u00edrito \u00e9 vida e paz\u201d.<\/span><span style=\"font-weight: 400;\">6<\/span><\/p>\n<h6><strong>Notas<br \/>\n<\/strong>1 \u2013 Jo\u00e3o 8.32.<br \/>\n2 \u2013 OWEN, John. <i>Pneumatologia <\/i>ou <i>A Discourse Concerning the Holy Spirit<\/i>.\u00a0[S.l.: s.n.]: 1668. p. 111.<br \/>\n3 \u2013 Romanos 12.2.<br \/>\n4 \u2013 Filipenses 4.8.<br \/>\n5 \u2013 Colossenses 3.1-2.<br \/>\n6 \u2013 Romanos 8.5-6.<\/h6>\n<pre><span style=\"font-weight: 400;\">Trecho do livro <\/span><a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/crer-e-tambem-pensar-1\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">Crer \u00e9 Tamb\u00e9m Pensar<\/span><\/i><\/a><span style=\"font-weight: 400;\">. ABU\/Ultimato, 2012.<\/span><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>No m\u00eas de mar\u00e7o, a Editora Ultimato\u00a0comemorou\u00a0junto com a Alian\u00e7a B\u00edblica Universit\u00e1ria (ABU)\u00a0os\u00a043 anos de\u00a0funda\u00e7\u00e3o da ABU Editora\u00a0e\u00a0os\u00a07 anos de parceria,\u00a0desde\u00a0que Ultimato passou a ser a respons\u00e1vel por comercializar os livros dessa editora. Atualmente Ultimato tem mais de 50 t\u00edtulos da ABU em seu\u00a0cat\u00e1logo. &nbsp; A seguir voc\u00ea pode ler um trecho de Crer \u00e9 [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[114,14852],"tags":[30087,14865,10707,9878,9508],"class_list":["post-1229","post","type-post","status-publish","format-standard","hentry","category-artigos","category-leia-um-trecho","tag-abu-editora","tag-crer-e-tambem-pensar","tag-mente","tag-santidade","tag-verdade"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/1229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/comments?post=1229"}],"version-history":[{"count":11,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/1229\/revisions"}],"predecessor-version":[{"id":1260,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/1229\/revisions\/1260"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/media?parent=1229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/categories?post=1229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/tags?post=1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}