{"id":1001,"date":"2017-09-19T06:00:38","date_gmt":"2017-09-19T09:00:38","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/john-stott\/?p=1001"},"modified":"2017-09-15T10:52:17","modified_gmt":"2017-09-15T13:52:17","slug":"ministerio-cristao-em-nosso-trabalho","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/john-stott\/2017\/09\/19\/ministerio-cristao-em-nosso-trabalho\/","title":{"rendered":"Minist\u00e9rio crist\u00e3o em nosso trabalho"},"content":{"rendered":"<blockquote><p>Ao falar sobre o servi\u00e7o dos crist\u00e3os a Cristo e ao pr\u00f3ximo, John Stott lembra que h\u00e1 diferentes tipos de minist\u00e9rio, conforme o dom e a voca\u00e7\u00e3o de cada servo. Cada um pode servir com suas ora\u00e7\u00f5es, dons, interesses e capacidades, encorajando ou engajando-se em alguma atividade e respondendo \u00e0 chamada de Deus para nos especializarmos de acordo com nossa voca\u00e7\u00e3o, conforme os dons, os interesses e oportunidades.<\/p><\/blockquote>\n<p>Al\u00e9m dos diferentes dons, h\u00e1 diferentes esferas do minist\u00e9rio crist\u00e3o, come\u00e7ando do nosso \u201ccentro\u201d pessoal (lar e trabalho), passando pela igreja e vizinhan\u00e7a, at\u00e9 atingir o mundo todo. A respeito do minist\u00e9rio crist\u00e3o em nosso trabalho ele diz:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-1005\" src=\"http:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_stott_ministerio_cristao_19_9_2017-300x199.jpg\" alt=\"\" width=\"220\" height=\"146\" srcset=\"https:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_stott_ministerio_cristao_19_9_2017-300x199.jpg 300w, https:\/\/ultimato.com.br\/sites\/john-stott\/files\/blog_stott_ministerio_cristao_19_9_2017.jpg 302w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>O local de trabalho \u00e9 a segunda esfera na qual somos chamados a servir, a exercitar um minist\u00e9rio crist\u00e3o. H\u00e1 crist\u00e3os que entendem isso apenas em termos de evangeliza\u00e7\u00e3o \u2013 acham que o seu emprego \u00e9 primordialmente uma oportunidade para testemunhar aos seus colegas ou companheiros de trabalho. Isso \u00e9 verdade, principalmente se eles forem os \u00fanicos crist\u00e3os ali, e especialmente se o seu testemunho se refletir acima de tudo na qualidade de seu trabalho. Mas o nosso trabalho di\u00e1rio tem o seu pr\u00f3prio valor como forma de minist\u00e9rio crist\u00e3o, totalmente independente da quest\u00e3o evangel\u00edstica. N\u00f3s precisamos de uma filosofia crist\u00e3 de trabalho.<\/p>\n<p>O lugar certo para come\u00e7ar \u00e9 em G\u00eanesis 1, onde vemos Deus como um trabalhador atencioso, criativo, diligente e respons\u00e1vel. Depois de criar o mundo, ele continuou supervisando, sustentando e renovando-o. Ent\u00e3o, ao criar os seres humanos \u00e0 sua pr\u00f3pria imagem, ele os fez igualmente trabalhadores criativos. Lembrar que ao trabalhar estamos sendo <em>como Deus<\/em> acrescenta honra e dignidade ao nosso labor. O nosso trabalho ganha ainda mais import\u00e2ncia porque nos permite beneficiar a outros, tanto porque ao ganhar nosso sal\u00e1rio podemos sustentar nossa fam\u00edlia e ajudar os necessitados, quanto porque o produto de nosso trabalho contribui para o bem comum.<\/p>\n<p><!--more-->Existe, no entanto, uma vis\u00e3o ainda mais nobre de trabalho. Deus quer que o vejamos como uma forma de cuidarmos do que \u00e9 dele por ordem dele, e at\u00e9 mesmo em parceria com ele, papel para o qual ele nos designou. Ele fez a terra e ent\u00e3o disse aos seres humanos que a sujeitassem e dominassem (G\u00eanesis 1.26-28). Ele plantou um jardim e ent\u00e3o colocou Ad\u00e3o ali para o cultivar e cuidar (G\u00eanesis 2.8, 15). Quer a tarefa seja global (a terra) ou local (o jardim do \u00c9den), o princ\u00edpio de mordomia era o mesmo. Deus repassou para administradores humanos a responsabilidade de proteger o meio ambiente e desenvolver seus recursos. Portanto, \u00e9 mais do que o papel de mordomos, em que Deus \u00e9 o senhor da terra e n\u00f3s gerenciamos sua propriedade; \u00e9 uma parceria genu\u00edna na qual Deus deliberadamente se humilha e pede a nossa colabora\u00e7\u00e3o. Ele cria; n\u00f3s cultivamos. Ele planta; n\u00f3s desenvolvemos. O que ele d\u00e1 se chama \u201cnatureza\u201d; a nossa contribui\u00e7\u00e3o chama-se \u201ccultivo\u201d. O cultivo \u00e9 imposs\u00edvel sem a natureza, j\u00e1 que n\u00e3o ter\u00edamos nada a cultivar se Deus n\u00e3o tivesse dado. Mas a natureza, por sua vez, tem valor limitado sem o cultivo, j\u00e1 que Deus nos deu a mat\u00e9ria-prima e deixou para n\u00f3s a tarefa de convert\u00ea-la em bens.<\/p>\n<p>Cada trabalho honrado, quer seja manual ou mental, ou os dois, quer seja assalariado ou volunt\u00e1rio, por mais simples e humilde que seja, deve ser visto pelo crist\u00e3o como uma esp\u00e9cie de coopera\u00e7\u00e3o com Deus, na qual n\u00f3s participamos com ele na transforma\u00e7\u00e3o do mundo que ele fez e submeteu aos nossos cuidados. Isto se aplica na mesma propor\u00e7\u00e3o a quem trabalha na ind\u00fastria e no com\u00e9rcio, em reparti\u00e7\u00f5es p\u00fablicas e em qualquer profiss\u00e3o, assim como a donas de casa e m\u00e3es de fam\u00edlia. O grande mal do desemprego \u00e9 que ele nega esse privil\u00e9gio a algumas pessoas. Agora, de que forma vamos exercer a nossa parceria com Deus \u2013 em termos seculares, que carreira vamos seguir, que empregos vamos assumir \u2013 depender\u00e1 mais do que tudo do nosso temperamento e talentos, da educa\u00e7\u00e3o e capacita\u00e7\u00e3o que recebemos. Todo crist\u00e3o deveria dar tudo de si com a maior satisfa\u00e7\u00e3o no servi\u00e7o de Deus, de modo que tudo o que somos e tudo o que temos nos traga realiza\u00e7\u00e3o, e n\u00e3o frustra\u00e7\u00e3o.<\/p>\n<pre>Trecho extra\u00eddo do livro <em><a href=\"http:\/\/www.ultimato.com.br\/loja\/produtos\/como-ser-cristao\" target=\"_blank\" rel=\"noopener\">Como Ser Crist\u00e3o<\/a>.<\/em><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Ao falar sobre o servi\u00e7o dos crist\u00e3os a Cristo e ao pr\u00f3ximo, John Stott lembra que h\u00e1 diferentes tipos de minist\u00e9rio, conforme o dom e a voca\u00e7\u00e3o de cada servo. Cada um pode servir com suas ora\u00e7\u00f5es, dons, interesses e capacidades, encorajando ou engajando-se em alguma atividade e respondendo \u00e0 chamada de Deus para nos [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[116,14852],"tags":[34796,5465,87,17737,6062,16533],"class_list":["post-1001","post","type-post","status-publish","format-standard","hentry","category-blog","category-leia-um-trecho","tag-como-ser-cristao","tag-dom","tag-ministerio","tag-servico","tag-trabalho","tag-vocacao"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/comments?post=1001"}],"version-history":[{"count":4,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/1001\/revisions"}],"predecessor-version":[{"id":1004,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/posts\/1001\/revisions\/1004"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/media?parent=1001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/categories?post=1001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/john-stott\/wp-json\/wp\/v2\/tags?post=1001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}