{"id":1443,"date":"2021-01-21T23:26:02","date_gmt":"2021-01-22T02:26:02","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/gladircabral\/?p=1443"},"modified":"2021-01-21T23:26:02","modified_gmt":"2021-01-22T02:26:02","slug":"racismo-e-religiosidade-em-a-mesa-do-senhor-de-alice-walker","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/gladircabral\/2021\/01\/21\/racismo-e-religiosidade-em-a-mesa-do-senhor-de-alice-walker\/","title":{"rendered":"Racismo e religiosidade em \u201cA Mesa do Senhor\u201d, de Alice Walker"},"content":{"rendered":"<p><a href=\"http:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1444 size-large\" src=\"http:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker-682x1024.jpg\" alt=\"\" width=\"682\" height=\"1024\" srcset=\"https:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker-682x1024.jpg 682w, https:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker-200x300.jpg 200w, https:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker-768x1154.jpg 768w, https:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker-1022x1536.jpg 1022w, https:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker-732x1100.jpg 732w, https:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker-1140x1713.jpg 1140w, https:\/\/ultimato.com.br\/sites\/gladircabral\/files\/2021\/01\/alice-walker.jpg 1174w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/a>H\u00e1 uma can\u00e7\u00e3o Negro Spiritual escrita no s\u00e9culo XIX que atravessou o s\u00e9culo XX e ganhou interpreta\u00e7\u00e3o famosa na voz de Clara Ward: \u201cI\u2019m gona walk and talk with Jesus\u201d, anunciando a recep\u00e7\u00e3o que Jesus dar\u00e1 aos convidados nas bodas do seu Reino, conforme est\u00e1 no livro de Apocalipse 19. A can\u00e7\u00e3o expressa um sonho de mudan\u00e7a diante da realidade de opress\u00e3o e viol\u00eancia em que vivia, e vive ainda, o povo afro-americano.<\/p>\n<p>O conto \u201cA Mesa do Senhor\u201d, escrito por Alice Walker (1970), \u00e9 inspirado na can\u00e7\u00e3o tradicional e dedicado \u00e0 cantora gospel Clara Ward (1924-1973). O conto faz lembrar a can\u00e7\u00e3o que fala do grande banquete prometido por Jesus aos que nele confia. Os escravos, que jamais puderam sequer sonhar em estar \u00e0 mesa com seus senhores, alimentavam o sonho de um dia estarem \u00e0 mesa com o Senhor dos senhores. \u00c9 desse sonho que o conto trata, um sonho atualizado para a Am\u00e9rica do Norte dos anos 1970.<\/p>\n<p>O conto se inicia com uma senhora idosa e humilde, vestida com roupas apropriadas, mas rotas e envelhecidas, para ir ao culto. Est\u00e1 diante de uma igreja toda branca. Essa mulher preta trabalhou a vida inteira como empregada dom\u00e9stica em casa de brancos. Seu rosto enigm\u00e1tico, envelhecido e fechado desafia interpreta\u00e7\u00f5es. A igreja \u00e9 branca, o bairro \u00e9 de brancos, ela \u00e9 que parece destoar. Num pa\u00eds onde a segrega\u00e7\u00e3o racial seguiu a liberta\u00e7\u00e3o dos escravos, tornou-se comum a estranha divis\u00e3o entre igrejas para prestos e igreja para brancos.<\/p>\n<p>Inadvertidamente, a mulher, que enxerga muito mal, entra numa igreja de brancos e \u00e9 recebida com frieza. O dia \u00e9 de inverno. Frio congelante na rua, um pouco menos frio dentro do templo, gelado nos cora\u00e7\u00f5es. Ap\u00f3s subir as escadarias, a mulher senta-se no \u00faltimo banco, contempla os vitrais e passa a adorar, cantando mentalmente algum hino antigo. Os fi\u00e9is chegam depois. A rea\u00e7\u00e3o deles \u00e9 de desconcerto, primeiro, depois irrita\u00e7\u00e3o, hostilidade e rejei\u00e7\u00e3o. O reverendo tenta convenc\u00ea-la de que ela est\u00e1 na igreja errada, \u201ccomo se fosse poss\u00edvel escolher a igreja errada\u201d. O jovem zelador da igreja tamb\u00e9m n\u00e3o conseguiu convenc\u00ea-la a sair. Foram as mulheres, cheias de indigna\u00e7\u00e3o, que for\u00e7aram seus maridos a \u201ctirarem dali a velha de cor\u201d.<\/p>\n<p>Uma vez expulsa da igreja, a mulher, perplexa, v\u00ea aproximar-se pela longa estrada uma figura conhecida: Jesus. Era o mesmo da imagem que tinha em sua casa: vestes brancas, sand\u00e1lias, olhos castanhos, como se sorrisse. Ao chegar perto dela, Ele disse: \u201cSegue-me\u201d. Os dois passam a caminhar juntos em sil\u00eancio profundo estrada afora, sorrindo e conversando. As pessoas da igreja nem tomaram conhecimento. \u201cAquela gente da igreja nunca soube o que aconteceu \u00e0 velha. [&#8230;] Algum tempo depois, eles ouviram falar que uma velha morrera em algum ponto da estrada\u201d.<\/p>\n<p>\u00c9 poss\u00edvel estar numa igreja e mesmo assim n\u00e3o enxergar o outro. \u00c9 poss\u00edvel estar na igreja e nem sequer enxergar a presen\u00e7a de Jesus. Ele vem para andar com o oprimido, o exclu\u00eddo, o desprezado. Ele traz o sorriso de Deus e um gesto de acolhimento. Sua gra\u00e7a transcende a aridez das institui\u00e7\u00f5es religiosas. Sua luz revela as sombras ocultas de nossa hipocrisia e nos mostra quem de fato somos.<\/p>\n<p>&nbsp;<\/p>\n<p>Gladir Cabral<\/p>\n<p>&nbsp;<\/p>\n<p>Alice Walker. <strong>De amor e desespero: hist\u00f3rias de mulheres negras. <\/strong>Trad. Wald\u00e9a Barcellos. Rio de Janeiro: Rocco, 1998.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 uma can\u00e7\u00e3o Negro Spiritual escrita no s\u00e9culo XIX que atravessou o s\u00e9culo XX e ganhou interpreta\u00e7\u00e3o famosa na voz de Clara Ward: \u201cI\u2019m gona walk and talk with Jesus\u201d, anunciando a recep\u00e7\u00e3o que Jesus dar\u00e1 aos convidados nas bodas do seu Reino, conforme est\u00e1 no livro de Apocalipse 19. A can\u00e7\u00e3o expressa um sonho [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1443","post","type-post","status-publish","format-standard","hentry","category-artigos"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":3,"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"predecessor-version":[{"id":1447,"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/posts\/1443\/revisions\/1447"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/gladircabral\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}