{"id":2459,"date":"2025-07-01T09:55:21","date_gmt":"2025-07-01T12:55:21","guid":{"rendered":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/?p=2459"},"modified":"2025-07-01T09:55:21","modified_gmt":"2025-07-01T12:55:21","slug":"a-vida-que-jorra","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/2025\/07\/01\/a-vida-que-jorra\/","title":{"rendered":"A vida que jorra"},"content":{"rendered":"<h4><\/h4>\n<h4 style=\"text-align: center;\"><span style=\"color: #993300;\">VIVER \u00c9 SEMPRE UMA TENTATIVA DE SER<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>Fugidia, a vida jorra, flui, extravasa. Seus movimentos giram e rodopiam nossas v\u00e3s compreens\u00f5es. Quanto mais passa, mais a vida se transforma e surpreende. Os ponteiros do rel\u00f3gio s\u00e3o apenas representa\u00e7\u00f5es; a realidade supera a matem\u00e1tica.<\/p>\n<p>J\u00e1 estamos no meio do caminho. Julho de 2025. Olho para tr\u00e1s ou olho para frente? Ambos. A sabedoria est\u00e1 na decis\u00e3o do olhar. No rumo que meus olhos tomam, na migra\u00e7\u00e3o dos sentidos e decis\u00f5es.<\/p>\n<p>O tempo escorre pelas m\u00e3os, mas a vida se parece mais com um transbordamento surpreendente do que com um vazamento imprevisto.<\/p>\n<p>Vale a pena tentar.<\/p>\n<p>Viver \u00e9 sempre uma tentativa de ser. Ser quem fomos chamados a ser desde o in\u00edcio. Ser a ess\u00eancia humana na poeira c\u00f3smica. Ser a imagem de Deus na confus\u00e3o de \u00eddolos, epifanias artificiais e cacofonias insensatas. Ser simples, ser verdadeiro.<\/p>\n<p>Que venha o segundo semestre! Que venha a vida &#8211; que j\u00e1 veio, mas ainda n\u00e3o. Veio, vem e vir\u00e1.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p class=\"dark:text-text-dark font-regular text-15 font-aktiv-grotesk leading-loose text-gray-50\">&#8220;No entanto, est\u00e1 chegando a hora, e de fato j\u00e1 chegou, em que os verdadeiros adoradores adorar\u00e3o o Pai em esp\u00edrito e em verdade. Estes s\u00e3o os adoradores que o Pai procura. Deus \u00e9 esp\u00edrito, e \u00e9 necess\u00e1rio que os seus adoradores o adorem em esp\u00edrito e em verdade&#8221; (Jo\u00e3o 4.23-24 &#8211; NVI).<\/p>\n<\/blockquote>\n<div class=\"flex flex-wrap items-center justify-end mbs-1\"><\/div>\n<div>Foto: <a href=\"https:\/\/pixabay.com\/pt\/photos\/p%C3%A1ssaro-cachoeira-6559677\/\">Pixabay\u00a0<\/a><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIVER \u00c9 SEMPRE UMA TENTATIVA DE SER &nbsp; Fugidia, a vida jorra, flui, extravasa. Seus movimentos giram e rodopiam nossas v\u00e3s compreens\u00f5es. Quanto mais passa, mais a vida se transforma e surpreende. Os ponteiros do rel\u00f3gio s\u00e3o apenas representa\u00e7\u00f5es; a realidade supera a matem\u00e1tica. J\u00e1 estamos no meio do caminho. Julho de 2025. Olho para [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":2460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[],"tags":[45466,45465,6048,6095],"class_list":["post-2459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-2semestre","tag-julho2025","tag-tempo","tag-vida"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/2459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/comments?post=2459"}],"version-history":[{"count":4,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/2459\/revisions"}],"predecessor-version":[{"id":2464,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/2459\/revisions\/2464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/media\/2460"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/media?parent=2459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/categories?post=2459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/tags?post=2459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}