{"id":2403,"date":"2024-06-06T09:09:34","date_gmt":"2024-06-06T12:09:34","guid":{"rendered":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/?p=2403"},"modified":"2024-06-06T09:09:34","modified_gmt":"2024-06-06T12:09:34","slug":"a-mentira-caminha-ao-lado-da-verdade","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/2024\/06\/06\/a-mentira-caminha-ao-lado-da-verdade\/","title":{"rendered":"A mentira caminha ao lado da verdade"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>O lugar preferido da mentira \u00e9 ao lado da verdade. O seu poder reside exatamente em parecer real. N\u00e3o s\u00e3o poucos os salmos que denunciam os \u201cl\u00e1bios bajuladores\u201d (Sl 12.2) e \u201cpessoas trai\u00e7oeiras\u201d (Sl 43.1). Mas esta \u00e9 s\u00f3 a ponta do iceberg da quest\u00e3o.<\/p>\n<p>A mentira sustenta culturas, religi\u00f5es, ci\u00eancias e ideologias. Ela cria um sistema l\u00f3gico e nos convence de que somos inteligentes quando o defendemos. Se engana quem pensa que \u00e9 f\u00e1cil discerni-la.<\/p>\n<p>A mentira tamb\u00e9m cria mundos ocultos e paralelos. Ela nos coloca em lugares falsos e nos faz acreditar que somos \u201cdonos do mundo\u201d. Foi o que Satan\u00e1s tentou fazer com Jesus: dar a ele imp\u00e9rios que n\u00e3o existiam (Mt 4.9).<\/p>\n<blockquote>\n<h3 style=\"text-align: right;\"><span style=\"color: #ff0000;\">\u00c9 perfeitamente poss\u00edvel esperarmos<br \/>\npor algo que nunca vai acontecer.<\/span><\/h3>\n<\/blockquote>\n<p>A mentira tamb\u00e9m ataca a esperan\u00e7a. \u00c9 perfeitamente poss\u00edvel esperarmos por algo que nunca vai acontecer. Seja uma ideia de mundo perfeito em que a evolu\u00e7\u00e3o do conhecimento levar\u00e1 o ser humano ao \u00e1pice do progresso, do bem-estar e da justi\u00e7a social. Seja a esperan\u00e7a de uma sociedade igualit\u00e1ria, livre de todos os preconceitos e plena em liberdade. Seja a f\u00e9 de que h\u00e1 um mundo fora deste onde eu, de fato, serei feliz como recompensa pelo meu bom comportamento. Seja acreditar que os astros definem meu destino ou que o papai Noel existe. Seja confiar na tecnologia como salva\u00e7\u00e3o para meu vazio mais profundo ou simplesmente esperar ser amado por conta da minha beleza f\u00edsica, meu poder financeiro, meu status social ou minha capacidade intelectual.<\/p>\n<p>Para tudo isso a mentira tem uma resposta convincente. Ela faz uso tanto do pessimismo quanto do otimismo. Das fragilidades ou das for\u00e7as. Como um camale\u00e3o, ela tem as vestimentas certas para as ocasi\u00f5es adequadas. Impercept\u00edvel, ela \u00e9 querida, amada e celebrada.<\/p>\n<p>Diariamente sou confrontado por minhas mentiras. Elas est\u00e3o sempre tentando me convencer a ser quem n\u00e3o sou. S\u00e3o muitas as oportunidades para isso. Minhas virtudes \u2013 que s\u00e3o genu\u00ednas \u2013 podem se tornar ferramentas eficazes nas m\u00e3os da mentira, moldando assim minha identidade em torno de proje\u00e7\u00f5es e desejos.<\/p>\n<p>Quando Cristo declara que ele \u00e9 \u201co caminho, a verdade e a vida\u201d (Jo 14.6), est\u00e1 dando um norte aos seus disc\u00edpulos. Em meio a um mundo turbulento e inseguro, Jesus os convida a descansar na sua verdade, no seu rumo, na sua proposta de vida.<\/p>\n<p>Aqui ent\u00e3o est\u00e1 uma escolha fundamental a ser feita: ou eu confio na Palavra ou eu confio nas m\u00faltiplas faces da mentira. Confiar na Palavra \u00e9 entregar-se ao Verbo. \u00c9 deixar-se levar pelos ecos da gra\u00e7a soprados pelo doce Vento do Esp\u00edrito e esvaziar-se das camadas de mentira que foram sendo colocadas em nosso cora\u00e7\u00e3o e em nossa mente.<\/p>\n<p>Este esfor\u00e7o \u00e9 muito grande, s\u00f3 poss\u00edvel por causa da Gra\u00e7a. Podemos crer que a Verdade \u00e9 forte o suficiente para nos libertar (Jo 8.32). Todos os dias e para sempre.<\/p>\n<hr \/>\n<p>Imagem: <a href=\"https:\/\/pixabay.com\/pt\/photos\/a-sombra-jogo-de-sombra-sombras-198682\/\">Pixabay<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O lugar preferido da mentira \u00e9 ao lado da verdade. O seu poder reside exatamente em parecer real. N\u00e3o s\u00e3o poucos os salmos que denunciam os \u201cl\u00e1bios bajuladores\u201d (Sl 12.2) e \u201cpessoas trai\u00e7oeiras\u201d (Sl 43.1). Mas esta \u00e9 s\u00f3 a ponta do iceberg da quest\u00e3o. A mentira sustenta culturas, religi\u00f5es, ci\u00eancias e ideologias. Ela [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":2404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[114],"tags":[8428,9508],"class_list":["post-2403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","tag-mentira","tag-verdade"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":6,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"predecessor-version":[{"id":2410,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/2403\/revisions\/2410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/media\/2404"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}