{"id":1349,"date":"2015-08-12T09:30:19","date_gmt":"2015-08-12T12:30:19","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/?p=1349"},"modified":"2015-08-12T09:30:59","modified_gmt":"2015-08-12T12:30:59","slug":"1349","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/2015\/08\/12\/1349\/","title":{"rendered":"No metr\u00f4, muitos Brasis"},"content":{"rendered":"<p>L\u00e1 est\u00e3o eles, rostos fechados, s\u00f3 mexendo as bocas com chicletes, dedos nos smartphones e, em alguns casos, fones nos ouvidos. S\u00e3o os usu\u00e1rios do metr\u00f4 de S\u00e3o Paulo. Gente de todo tipo, mas com comportamentos bem parecidos.<\/p>\n<p>Mas eis que uma turma entra no metr\u00f4, falando alto, rindo. Juntam-se no mesmo lugar. De repente, outro amigo tamb\u00e9m entra no metr\u00f4. Aumenta o volume das falas e dos risos. Seguimos umas sete esta\u00e7\u00f5es assim, at\u00e9 a esta\u00e7\u00e3o S\u00e3o Judas.<\/p>\n<p>O que somos? Intrusos, passageiros ou caipiras? A verdade \u00e9 que somos quase todos do interior: Minas, Paran\u00e1, Goi\u00e1s&#8230;<\/p>\n<p>A Grande S\u00e3o Paulo nos suporta. Ela \u00e9 generosa, suporta muita gente. Talvez n\u00e3o devamos esperar que os outros passageiros esbocem sorrisos. Tudo bem. S\u00f3 nos permitirem permanecer no metr\u00f4 j\u00e1 est\u00e1 de bom tamanho.<\/p>\n<p>Na volta, uma voz informa no microfone: &#8220;usu\u00e1rios na pista. Teremos que parar por enquanto&#8221;. E assim esperamos, com o olho no rel\u00f3gio e com medo de perdermos o \u00faltimo \u00f4nibus para Vi\u00e7osa. Uma mo\u00e7a ao meu lado comenta algo sobre a situa\u00e7\u00e3o. A pol\u00edcia se movimenta na esta\u00e7\u00e3o em que o metr\u00f4 est\u00e1 parado. Demora um pouco para sairmos, mas, enfim, chegamos ao Tiet\u00ea. Agora \u00e9 entrar no \u00f4nibus e viajar por 12 horas de S\u00e3o Paulo \u00e0 Minas.<\/p>\n<p>Um dia depois, agora me lembro dos rostos dos usu\u00e1rios do metr\u00f4. Eu, que neste momento, digito em meu computador, perto de mato e vacas.<\/p>\n<p>O Brasil \u00e9 realmente fascinante. De tantas diferen\u00e7as, n\u00e3o d\u00e1 para criar discursos iguais e previs\u00edveis. Parece que nossa grande tarefa \u00e9 descobrir os princ\u00edpios que regem nosso cora\u00e7\u00e3o. Num pa\u00eds cheio de &#8220;slogans&#8221; e &#8220;frases feitas&#8221;, cabe a n\u00f3s n\u00e3o perdermos o bonde da hist\u00f3ria. Ou seria o metr\u00f4?<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00e1 est\u00e3o eles, rostos fechados, s\u00f3 mexendo as bocas com chicletes, dedos nos smartphones e, em alguns casos, fones nos ouvidos. S\u00e3o os usu\u00e1rios do metr\u00f4 de S\u00e3o Paulo. Gente de todo tipo, mas com comportamentos bem parecidos. Mas eis que uma turma entra no metr\u00f4, falando alto, rindo. Juntam-se no mesmo lugar. De repente, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7654],"tags":[7604],"class_list":["post-1349","post","type-post","status-publish","format-standard","hentry","category-cronicas","tag-cronicas-de-viagem"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/1349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/comments?post=1349"}],"version-history":[{"count":2,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/1349\/revisions"}],"predecessor-version":[{"id":1351,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/posts\/1349\/revisions\/1351"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/media?parent=1349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/categories?post=1349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/fatosecorrelatos\/wp-json\/wp\/v2\/tags?post=1349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}