{"id":2841,"date":"2021-07-09T13:00:00","date_gmt":"2021-07-09T16:00:00","guid":{"rendered":"https:\/\/ultimato.com.br\/sites\/elbencesar\/?p=2841"},"modified":"2021-07-09T13:00:00","modified_gmt":"2021-07-09T16:00:00","slug":"o-clamor-de-habacuque","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/elbencesar\/2021\/07\/09\/o-clamor-de-habacuque\/","title":{"rendered":"O clamor de Habacuque"},"content":{"rendered":"<p><a href=\"https:\/\/ultimato.com.br\/sites\/elbencesar\/files\/2021\/07\/clamor-habacuque.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-2842\" src=\"https:\/\/ultimato.com.br\/sites\/elbencesar\/files\/2021\/07\/clamor-habacuque.jpg\" alt=\"\" width=\"149\" height=\"99\" \/><\/a>O profeta Habacuque foi contempor\u00e2neo de Jeremias e viveu numa \u00e9poca de crescente deteriora\u00e7\u00e3o moral e espiritual em Jud\u00e1 (o reino do sul). Ele sabia que o ju\u00edzo de Deus se aproximava e viria por meio da invas\u00e3o babil\u00f4nica, ocorrida em 586 antes de Cristo. Ele n\u00e3o se conformava com a iniq\u00fcidade do seu povo nem com o avan\u00e7o de Nabucodonosor.<\/p>\n<p>\u00c9 nesse contexto que aparece o famoso clamor de Habacuque: \u201cSenhor, ouvi falar da tua fama; tremo diante dos teus atos, Senhor. Realiza de novo, em nossa \u00e9poca, as mesmas obras, faze-as conhecidas em nosso tempo; em tua ira, lembra-te da miseric\u00f3rdia\u201d (Hc 3.2).<\/p>\n<p>Lembrando-se dos atos portentosos de Deus na hist\u00f3ria da na\u00e7\u00e3o, principalmente, quem sabe, do \u00eaxodo do povo de Israel do Egito, o profeta roga ao Senhor que fa\u00e7a novamente as mesmas obras realizadas no passado. \u00c9 por essa raz\u00e3o que os crentes costumam usar a ora\u00e7\u00e3o de Habacuque para clamar a Deus por um avivamento na igreja.<\/p>\n<p>Outras vers\u00f5es das Escrituras ajudam a compreender melhor o clamor de Habacuque:<\/p>\n<p>\u201cEdi\u00e7\u00e3o Revista e Atualizada\u201d &#8212; \u201cAviva a tua obra, \u00f3 Senhor, no decorrer dos anos, e, no decurso dos anos, faze-a conhecida\u201d.<\/p>\n<p>\u201cNova Tradu\u00e7\u00e3o na Linguagem de Hoje\u201d &#8212; \u201cFaze agora, em nosso tempo, as coisas maravilhosas que fizeste no passado, para que n\u00f3s tamb\u00e9m as vejamos\u201d.<\/p>\n<p>\u201cB\u00edblia Hebraica\u201d &#8212; \u201c\u00d3 Eterno, mant\u00e9m sempre viva tua obra [Israel] ao longo dos anos [de ex\u00edlio]. No correr do tempo torna-a reconhecida\u201d.<\/p>\n<p>\u201cNa Edi\u00e7\u00e3o Pastoral\u201d &#8212; \u201cAo correr dos anos faze-as [as tuas obras] reviver; manifesta-as no curso dos anos\u201d. (Outras tr\u00eas tradu\u00e7\u00f5es usam o mesmo verbo \u2018reviver\u2019.)<\/p>\n<p>\u201cB\u00edblia do Peregrino\u201d &#8211;\u201cNo meio dos anos realiza a tua a\u00e7\u00e3o! No meio dos anos, manifesta-a\u201d.<\/p>\n<p>\u201cB\u00edblia Viva\u201d &#8212; \u201cNesta hora em que precisamos tanto da ajuda, ajude-nos novamente, como fez no passado! Mostre o seu poder, que pode nos salvar\u201d.<\/p>\n<p>O clamor de Habacuque \u00e9 definido e preciso quanto ao que pede e quanto \u00e0 ocasi\u00e3o para a qual pede: \u201cQue o Senhor realize sua a\u00e7\u00e3o e a fa\u00e7a perceber no meio da hist\u00f3ria, sem adi\u00e1-la para um futuro indeterminado\u201d (par\u00e1frase de Lu\u00eds Alonso Sh\u00f6kel).<\/p>\n<p>Essa s\u00faplica, feita pessoal e comunitariamente, pode provocar saud\u00e1veis reviravoltas no povo de Deus, desde que saia mais do cora\u00e7\u00e3o do que dos l\u00e1bios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O profeta Habacuque foi contempor\u00e2neo de Jeremias e viveu numa \u00e9poca de crescente deteriora\u00e7\u00e3o moral e espiritual em Jud\u00e1 (o reino do sul). Ele sabia que o ju\u00edzo de Deus se aproximava e viria por meio da invas\u00e3o babil\u00f4nica, ocorrida em 586 antes de Cristo. Ele n\u00e3o se conformava com a iniq\u00fcidade do seu povo [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[116],"tags":[],"class_list":["post-2841","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts\/2841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/comments?post=2841"}],"version-history":[{"count":1,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts\/2841\/revisions"}],"predecessor-version":[{"id":2843,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts\/2841\/revisions\/2843"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/media?parent=2841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/categories?post=2841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/tags?post=2841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}