{"id":2626,"date":"2021-02-02T09:19:56","date_gmt":"2021-02-02T12:19:56","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/elbencesar\/?p=2626"},"modified":"2022-06-10T08:15:40","modified_gmt":"2022-06-10T11:15:40","slug":"o-sucesso-do-espirito","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/elbencesar\/2021\/02\/02\/o-sucesso-do-espirito\/","title":{"rendered":"O sucesso do Esp\u00edrito"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2664 \" title=\"Ilustra\u00e7\u00e3o: Cristina Balit (B\u00edblia para Crian\u00e7as, Editora Sinodal).\" src=\"http:\/\/ultimato.com.br\/sites\/elbencesar\/files\/2021\/02\/blog_EC_5-3-2021_sucesso-Espirito-226x300.jpg\" alt=\"\" width=\"267\" height=\"354\" srcset=\"https:\/\/ultimato.com.br\/sites\/elbencesar\/files\/2021\/02\/blog_EC_5-3-2021_sucesso-Espirito-226x300.jpg 226w, https:\/\/ultimato.com.br\/sites\/elbencesar\/files\/2021\/02\/blog_EC_5-3-2021_sucesso-Espirito.jpg 500w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/>Um dos minist\u00e9rios do Esp\u00edrito Santo \u00e9 fornecer a capacita\u00e7\u00e3o extra-humana para o servi\u00e7o prestado a Deus. \u00c9 por esta raz\u00e3o que os disc\u00edpulos deveriam permanecer em Jerusal\u00e9m \u00e0 espera do batismo especial do Esp\u00edrito, por meio do qual receberiam poder para serem testemunhas de Jesus em todo o mundo de ent\u00e3o (At 1.4-8). Coisa parecida aconteceu com Bezalel, o art\u00edfice principal do Tabern\u00e1culo.\u00a0 Est\u00e1 registrado que \u201co Esp\u00edrito de Deus o encheu de habilidade, intelig\u00eancia e conhecimento, em todo artif\u00edcio, e para elaborar desenhos e trabalhar em ouro, em prata, em bronze, para lapida\u00e7\u00e3o de pedras de engaste, para entalhe de madeira, para toda a sorte de lavores\u201d (\u00cax 35.31-33).<\/p>\n<p>A intera\u00e7\u00e3o entre o Esp\u00edrito e a Igreja \u00e9 tanta que o pecado de Ananias e Safira foi contra o Esp\u00edrito Santo: eles mentiram ao Esp\u00edrito e n\u00e3o aos homens (At 5.3-9). Outra evid\u00eancia dessa intera\u00e7\u00e3o est\u00e1 no pr\u00f3logo da ep\u00edstola de Jerusal\u00e9m: \u201cPareceu bem ao Esp\u00edrito Santo e a n\u00f3s (os ap\u00f3stolos)&#8230;\u201d (At 15.28).<\/p>\n<p>Como tal, o Esp\u00edrito tem direitos sobre a Igreja, como claramente se v\u00ea em Atos. Tem o direito de <em>cair<\/em> tanto sobre judeus como sobre gentios: \u201cQuando, por\u00e9m, comecei a falar, caiu o Esp\u00edrito Santo sobre eles, como tamb\u00e9m sobre n\u00f3s no princ\u00edpio\u201d (11.15). Tem o direito de <em>presidir<\/em>,<em> dirigir<\/em> ou <em>comandar<\/em>: ele mandou Filipe para a banda do sul (8.26), Pedro para a casa de Corn\u00e9lio (10.19-20) e Paulo e Barnab\u00e9 para os campos mission\u00e1rios mais distantes (13.2), e ainda impediu que Paulo e Tim\u00f3teo se dirigissem para a \u00c1sia e para a Bit\u00ednia. levando-os finalmente para a Maced\u00f4nia (16.6-10). Tem o direito de <em>encher<\/em> n\u00e3o s\u00f3 os ap\u00f3stolos, mas tamb\u00e9m homens como Est\u00eav\u00e3o (7.55), Barnab\u00e9 (11.24), Paulo (13.9) e a coletividade toda (2.4; 4.31).<\/p>\n<p>Os crist\u00e3os primitivos aprenderam a arte de reprimir a carne com o aux\u00edlio sobrenatural do Esp\u00edrito (Rm 8.13). Aprenderam a andar no Esp\u00edrito e n\u00e3o na carne (Gl 5.16 e 25). Aprenderam a colher o fruto do Esp\u00edrito em lugar de produzir as obras da carne (Gl 5.16-24). Eram exortados a n\u00e3o entristecer (Ef 4.32) e muito menos a apagar o Esp\u00edrito (1Ts 5.19). Eram convidados a se encher do Esp\u00edrito sempre que, por qualquer neglig\u00eancia ou circunst\u00e2ncia adversa, houvesse alguma quebra na plenitude (Ef 5.30).<\/p>\n<p>Enquanto tudo isso acontecia internamente, o Esp\u00edrito, do lado de fora, continuava a convencer \u201co mundo do pecado, da justi\u00e7a e do ju\u00edzo\u201d (Jo 16.8-11), sem o que n\u00e3o pode haver novas convers\u00f5es e novos acr\u00e9scimos.<\/p>\n<blockquote><p>N\u00e3o se deve pensar que o Esp\u00edrito Santo hoje j\u00e1 deu o que tinha para dar e se tornou uma esp\u00e9cie de Par\u00e1clito Em\u00e9rito. N\u00e3o existe semelhante absurdo no vocabul\u00e1rio crist\u00e3o!<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<pre>Publicado originalmente na edi\u00e7\u00e3o 207, outubro de 1990, da revista <strong>Ultimato<\/strong>.<\/pre>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos minist\u00e9rios do Esp\u00edrito Santo \u00e9 fornecer a capacita\u00e7\u00e3o extra-humana para o servi\u00e7o prestado a Deus. \u00c9 por esta raz\u00e3o que os disc\u00edpulos deveriam permanecer em Jerusal\u00e9m \u00e0 espera do batismo especial do Esp\u00edrito, por meio do qual receberiam poder para serem testemunhas de Jesus em todo o mundo de ent\u00e3o (At 1.4-8). Coisa [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[116],"tags":[27376,5411,5505,102,38],"class_list":["post-2626","post","type-post","status-publish","format-standard","hentry","category-blog","tag-batismo","tag-cristianismo","tag-espirito-santo","tag-evangelho","tag-igreja"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts\/2626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/comments?post=2626"}],"version-history":[{"count":5,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts\/2626\/revisions"}],"predecessor-version":[{"id":2665,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/posts\/2626\/revisions\/2665"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/media?parent=2626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/categories?post=2626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/elbencesar\/wp-json\/wp\/v2\/tags?post=2626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}