{"id":531,"date":"2015-10-10T19:06:00","date_gmt":"2015-10-10T22:06:00","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/casamentoefamilia\/?p=531"},"modified":"2015-10-10T19:24:44","modified_gmt":"2015-10-10T22:24:44","slug":"que-tal-um-final-de-semana-em-rio-das-ostras-rj","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/2015\/10\/10\/que-tal-um-final-de-semana-em-rio-das-ostras-rj\/","title":{"rendered":"QUE TAL UM FINAL DE SEMANA EM RIO DAS OSTRAS, RJ?"},"content":{"rendered":"<p>A Igreja Congregacional Venda das Pedras em Itabora\u00ed, RJ est\u00e1 promovendo o primeiro encontro do Programa de Enriquecimento Matrimonial nos dias 23 a 25\/10 e escolheram um local bem especial: o Vilarejo Praia Hotel em Rio das Ostras, regi\u00e3o dos Lagos no Rio de Janeiro. O casal que est\u00e1 \u00e0 frente da coordena\u00e7\u00e3o deste evento \u00e9 o Williams e a Mary Cabral e voc\u00ea pode ter mais informa\u00e7\u00f5es com eles pelo e-mail:\u00a0<a href=\"mailto: igrejavendadaspedras@gmail.com\">igrejavendadaspedras@gmail.com<\/a> ou pelos fones: (21) 99915-5676 ou (21) 2635-7602.<a href=\"http:\/\/ultimato.com.br\/sites\/casamentoefamilia\/files\/2015\/10\/news_rio_ostras1.png\" class=\"lightview\" data-lightview-group=\"group-531\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-527 size-full\" src=\"http:\/\/ultimato.com.br\/sites\/casamentoefamilia\/files\/2015\/10\/news_rio_ostras1.png\" alt=\"news_rio_ostras1\" width=\"641\" height=\"399\" srcset=\"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/files\/2015\/10\/news_rio_ostras1.png 641w, https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/files\/2015\/10\/news_rio_ostras1-300x187.png 300w, https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/files\/2015\/10\/news_rio_ostras1-150x93.png 150w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Igreja Congregacional Venda das Pedras em Itabora\u00ed, RJ est\u00e1 promovendo o primeiro encontro do Programa de Enriquecimento Matrimonial nos dias 23 a 25\/10 e escolheram um local bem especial: o Vilarejo Praia Hotel em Rio das Ostras, regi\u00e3o dos Lagos no Rio de Janeiro. O casal que est\u00e1 \u00e0 frente da coordena\u00e7\u00e3o deste evento [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[11681,116],"tags":[],"class_list":["post-531","post","type-post","status-publish","format-standard","hentry","category-acontece","category-blog"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/posts\/531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/comments?post=531"}],"version-history":[{"count":1,"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/posts\/531\/revisions"}],"predecessor-version":[{"id":532,"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/posts\/531\/revisions\/532"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/media?parent=531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/categories?post=531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/casamentoefamilia\/wp-json\/wp\/v2\/tags?post=531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}