{"id":9085,"date":"2017-04-25T11:40:25","date_gmt":"2017-04-25T14:40:25","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/?p=9085"},"modified":"2017-04-25T11:44:50","modified_gmt":"2017-04-25T14:44:50","slug":"a-igreja-brasileira-sofre-de-preguica-mental","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/2017\/04\/25\/a-igreja-brasileira-sofre-de-preguica-mental\/","title":{"rendered":"A igreja brasileira sofre de pregui\u00e7a mental"},"content":{"rendered":"<h6><span style=\"color: #993300;\"><strong>NA VARANDA COM GABRIELE GREGGERSEN<\/strong><\/span><\/h6>\n<p>Se voc\u00ea \u00e9 f\u00e3 de C. S. Lewis ou curte literatura fant\u00e1stica, provavelmente j\u00e1 deve ter lido algo assinado por ela, que \u00e9 autora de \u201cAntropologia Filos\u00f3fica de C. S. Lewis\u201d (Editora Mackenzie), de \u201cO Senhor dos An\u00e9is: da imagina\u00e7\u00e3o \u00e0 \u00e9tica\u201d, (Editora Ultimato) e mais de uma dezena de artigos publicado no portal Ultimato sobre Lewis. Al\u00e9m de tradutora, pedagoga, mestre e doutora em Hist\u00f3ria e Filosofia da Educa\u00e7\u00e3o, tamb\u00e9m \u00e9 te\u00f3loga.<\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/selo_navaranda.jpg\" class=\"lightview\" data-lightview-group=\"group-9085\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9092 alignright\" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/selo_navaranda.jpg\" alt=\"\" width=\"402\" height=\"100\" srcset=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/selo_navaranda.jpg 402w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/selo_navaranda-300x75.jpg 300w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/><\/a>Mas, sem muita cerim\u00f4nia. Prepare um caf\u00e9 ou um ch\u00e1 e venha para a varanda com Gabriele Greggersen, jogar conversa fora. \u00c9 com ela que Ultimato lan\u00e7a <strong>\u201cNa Varanda com o Autor\u201d<\/strong>, uma s\u00e9rie de entrevistas com autores e colunistas da revista e do portal Ultimato.<\/p>\n<p>Ah! E n\u00e3o vamos conversar sobre N\u00e1rnia&#8230;<\/p>\n<p><strong>Ultimato \u2013 Alguma pessoa ou livro, em especial, influenciou sua aproxima\u00e7\u00e3o da leitura e da escrita?<\/strong><\/p>\n<p><strong>Gabriele Greggersen \u2013<\/strong> Gosto muito de ler, mas meu gosto pelos bons livros foi despertado apenas no per\u00edodo da minha primeira faculdade, que foi de pedagogia. Nesse per\u00edodo, conheci excelentes autores, tanto crist\u00e3os quanto n\u00e3o crist\u00e3os \u2013 se \u00e9 que \u00e9 poss\u00edvel separ\u00e1-los de forma t\u00e3o r\u00edgida. Poucos sabem, por exemplo, que Paulo Freire foi crist\u00e3o cat\u00f3lico e costumam acus\u00e1-lo de desviar os estudantes crist\u00e3os da f\u00e9 \u2013, e \u00e0s vezes tinha dificuldades em concili\u00e1-los. C. S. Lewis foi um autor que me ajudou a fazer isso: a ser uma crist\u00e3 leitora, sem ser uma leitora necessariamente de obras apenas crist\u00e3s. Ele me ajudou tamb\u00e9m a achar a raz\u00e3o da minha f\u00e9, que Paulo tanto nos exorta para estarmos prontos a apresentar. E, com isso, fui preservada de perd\u00ea-la em meio aos autores ditos n\u00e3o crist\u00e3os \u2013 que me agradavam \u2013 os quais a desafiavam.<!--more--><\/p>\n<div id=\"attachment_9087\" style=\"width: 160px\" class=\"wp-caption alignright\"><a href=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/Na-varanda-gabriele02.jpg\" class=\"lightview\" data-lightview-group=\"group-9085\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9087\" class=\"wp-image-9087 size-thumbnail\" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/Na-varanda-gabriele02-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\"><\/a><p id=\"caption-attachment-9087\" class=\"wp-caption-text\">Nascida em Cascavel (PR), Gabriele mora atualmente no Rio de Janeiro (Foto: Arquivo pessoal)<\/p><\/div>\n<p>Mas para falar de outros autores, pois sou suspeita com rela\u00e7\u00e3o a esse, por motivos \u00f3bvios, vou cit\u00e1-los como vierem \u00e0 minha mente: ap\u00f3stolo Paulo e autores da B\u00edblia, Josef Pieper, Luigi Giussani, Juli\u00e1n Mar\u00edas, Marx e Engels, Gramsci, Makareko, Freud, Kapra, Kosik, Victor Frankl, Rudolf Otto, George Snyders, Paulo Freire, Santo Agostinho, Santo Tom\u00e1s, Plat\u00e3o e Arist\u00f3teles, Dietrich Bonhoeffer, John Stott, John Piper, Martinho Lutero, Jo\u00e3o Calvino, Rubem Alves, Timothy Keller e tantos outros, sem falar dos autores cl\u00e1ssicos da literatura mundial e brasileira.<\/p>\n<p>Todos eles despertaram, alimentaram e agu\u00e7aram em mim o gosto pela leitura e escrita e me tornaram a escritora que sou.<\/p>\n<p><strong>Ultimato \u2013 Quando a inspira\u00e7\u00e3o para escrever n\u00e3o vem&#8230;<\/strong><\/p>\n<p><strong>G. G. \u2013<\/strong> Eu dou uma corrida na praia e vou ouvir m\u00fasica ou assistir um filme ou conversar com amigos. Orar tamb\u00e9m ajuda bastante&#8230;<\/p>\n<p><strong>Ultimato \u2013 O que os adultos devem ler para as crian\u00e7as?<\/strong><\/p>\n<p><strong> G. G. \u2013 <\/strong>Eles devem ler o que gostavam de ler quando crian\u00e7as. Recomendo que leiam a literatura que tamb\u00e9m seria apreciada por adultos, e n\u00e3o \u00e9 \u201ccoisa de crian\u00e7a\u201d, pois a \u201ccoisa\u201d que a gente acha que seja \u201cpara crian\u00e7a\u201d normalmente \u00e9 rid\u00edcula e intrag\u00e1vel tanto para crian\u00e7a, quanto para adulto.<\/p>\n<p>E esses s\u00e3o os cl\u00e1ssicos, provados pelo tempo, n\u00e3o apenas contos de fada e a mitologia\/folclore, mas tamb\u00e9m as obras infantis de grandes autores como C.S. Lewis, J.R.R. Tolkien, Lewis Carrol, Mark Twain, Andersen, Antoine de Saint-Exup\u00e9ry, James Barrie, na literatura mundial; e, na brasileira, Monteiro Lobato, Malba Tahan, Ziraldo, Lygia Bojunga, Ana Maria Machado, Tatiana Belinsky, Ruth Rocha, Clarice Lispector, Cec\u00edlia Meireles, Raquel de Queiroz, Marina Colasanti. Mas jamais deve-se esquecer o ingrediente b\u00e1sico que \u00e9 (al\u00e9m do mais puro prazer, imagina\u00e7\u00e3o e alegria) o discernimento necess\u00e1rio a toda literatura, quer infantil, quer adulta.<\/p>\n<p><strong>Ultimato \u2013 Que conselho voc\u00ea gostaria de ter recebido na sua juventude?<\/strong><\/p>\n<p><strong> G. G. \u2013 <\/strong>Viva mais e leve tudo menos a s\u00e9rio. Mas nem todos os jovens precisam desse conselho.<\/p>\n<p><strong>Ultimato \u2013 O que mais a anima e o que mais a incomoda no meio evang\u00e9lico?<\/strong><\/p>\n<p><strong>G. G. \u2013<\/strong> O que mais me anima \u00e9 ver a imagem de Cristo refletida de formas t\u00e3o coloridas e multiformes nos crist\u00e3os, individualmente e quando est\u00e3o reunidos, que \u00e9 um espet\u00e1culo \u00e0 parte, principalmente, quando as pessoas demonstram leg\u00edtimo amor umas pelas outras.<\/p>\n<p>O que me incomoda, particularmente na igreja brasileira, \u00e9 o que chamo de pregui\u00e7a mental: a falta de leitura, a falta de h\u00e1bito do racioc\u00ednio l\u00f3gico e do debate. Parece que as pessoas querem tudo mastigado e pronto: f\u00f3rmulas m\u00e1gicas; a pergunta do \u201ccomo\u201d, que sempre pede uma receita de bolo (quem \u00e9 que j\u00e1 n\u00e3o foi numa palestra instigante em que, na hora da abertura para perguntas, se \u00e9 que algu\u00e9m pergunta alguma coisa, ou alguma coisa inteligente, algu\u00e9m vem com essa).<\/p>\n<p>Penso que esse defeito leve a in\u00fameros outros males: os v\u00e1rios tipos de preconceito e formas de exclus\u00e3o; as supersti\u00e7\u00f5es e cren\u00e7as her\u00e9ticas na igreja; o \u201cMaria vai com as outras\u201d e os modismos; a fofoca e maledic\u00eancia; o orgulho e soberba (pois quem pensa direito sabe que n\u00e3o valeria nada sem Deus e que esse \u00e9 o pecado capital que levou \u00e0 Queda da humanidade e do pr\u00f3prio Diabo); e finalmente todas as formas de corrup\u00e7\u00e3o (os corruptos n\u00e3o s\u00e3o, no fundo, os mais burros esp\u00e9cimes da ra\u00e7a humana, como a pol\u00edtica brasileira est\u00e1 cansada de demonstrar?)<\/p>\n<div id=\"attachment_9086\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/Na-varanda-gabriele01.jpg\" class=\"lightview\" data-lightview-group=\"group-9085\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9086\" class=\"wp-image-9086 size-medium\" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/Na-varanda-gabriele01-300x222.jpg\" alt=\"\" width=\"300\" height=\"222\" srcset=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/Na-varanda-gabriele01-300x222.jpg 300w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2017\/04\/Na-varanda-gabriele01.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-9086\" class=\"wp-caption-text\">Gabriele com o esposo Daniel Rangel Cabral Jr. (Foto: Arquivo pessoal)<\/p><\/div>\n<p><strong>Ultimato \u2013 Como voc\u00ea lida com o envelhecer?<\/strong><\/p>\n<p><strong> G. G. \u2013 <\/strong>Com naturalidade. Est\u00e1 certo que \u00e0s vezes a gente entra em p\u00e2nico com a ideia de um dia ser uma pessoa idosa, e ser tratada como tal (o que \u00e9 mais pavoroso), mas s\u00e3o raros. Na maioria das vezes, sou tomada pela convic\u00e7\u00e3o de que cada idade tem a sua beleza e encanto e momento certo para acontecer. Sempre fui precoce, de modo que em muitas coisas j\u00e1 penso feito uma idosa; mas em outras, pare\u00e7o uma crian\u00e7a. Ent\u00e3o, o que penso \u00e9 que sempre se tem que cuidar do equil\u00edbrio entre o anci\u00e3o e s\u00e1bio em si mesmo, e a crian\u00e7a, a quem pertence o Reino de Deus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NA VARANDA COM GABRIELE GREGGERSEN<br \/>\nSe voc\u00ea \u00e9 f\u00e3 de C. S. Lewis ou curte literatura fant\u00e1stica, provavelmente j\u00e1 deve ter lido algo assinado por ela, que \u00e9 autora de \u201cAntropologia Filos\u00f3fica de C. S. Lewis\u201d (Editora Mackenzie), de \u201cO Senhor dos An\u00e9is: da imagina\u00e7\u00e3o \u00e0 \u00e9tica\u201d, (Editora Ultimato) e mais de uma dezena de artigos [&#8230;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[32239],"tags":[5497,22283,32239],"class_list":["post-9085","post","type-post","status-publish","format-standard","hentry","category-na-varanda-com-o-autor","tag-entrevista","tag-gabriele-greggersen","tag-na-varanda-com-o-autor"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/9085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/comments?post=9085"}],"version-history":[{"count":13,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/9085\/revisions"}],"predecessor-version":[{"id":9107,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/9085\/revisions\/9107"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/media?parent=9085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/categories?post=9085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/tags?post=9085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}