{"id":14453,"date":"2020-02-20T12:06:45","date_gmt":"2020-02-20T14:06:45","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/?p=14453"},"modified":"2020-02-20T12:09:36","modified_gmt":"2020-02-20T14:09:36","slug":"um-chamado-um-caminho-uma-vida","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/2020\/02\/20\/um-chamado-um-caminho-uma-vida\/","title":{"rendered":"Um chamado, um caminho, uma vida&#8230;"},"content":{"rendered":"<p><span style=\"color: #808000;\"><strong>Por Luciana Brito<\/strong><\/span><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana.jpg\" class=\"lightview\" data-lightview-group=\"group-14453\" data-lightview-options=\"skin: 'dark', controls: 'relative', padding: '10', shadow: { color: '#000000', opacity: 0.08, blur: 3 }\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-14454 alignright\" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana-300x207.jpg\" alt=\"\" width=\"300\" height=\"207\" srcset=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana-300x207.jpg 300w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana-1024x707.jpg 1024w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana-768x530.jpg 768w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana-1536x1061.jpg 1536w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana-732x505.jpg 732w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana-1140x787.jpg 1140w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2020\/02\/blog_ult_20_2_20_OMLM_luciana.jpg 1787w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Passei minha inf\u00e2ncia e adolesc\u00eancia entre idas \u00e0 escola dominical, acampamentos e viagens ao interior para o s\u00edtio da fam\u00edlia. Perfil muito comum de fam\u00edlias da f\u00e9 em Goi\u00e1s.<\/p>\n<p>Por\u00e9m, aos quinze anos, tive uma breve no\u00e7\u00e3o do que estava preparado para mim. Deus falou comigo que me levaria para lugares distantes e que eu viveria para ele. Escrevi uma carta para conseguir expressar \u00e0 minha m\u00e3e o que havia acontecido. Li para ela no mesmo dia, mas ela n\u00e3o deu aten\u00e7\u00e3o, seu foco era o fog\u00e3o de lenha. Entendi que este caminho seria um tanto solit\u00e1rio&#8230;<\/p>\n<p>Segui o curso \u201cnatural\u201d da vida. Terminei o ensino m\u00e9dio e entrei na faculdade de veterin\u00e1ria no interior de Minas Gerais. Tanto na escola como na universidade eu participava das atividades de clubes do Bom Livro, da ABS e da ABU, respectivamente. Aquele chamado n\u00e3o me deixava inerte ao meio que eu vivia.<\/p>\n<p>Durante a faculdade foi o per\u00edodo que mais conheci ao Senhor. E, ao final do curso, sabia que era a hora de partir. Minha comunidade da f\u00e9 me apoiou e me enviou para um curso preparat\u00f3rio no minist\u00e9rio. L\u00e1 participei de v\u00e1rios trabalhos, treinamentos, e o mais marcante, que foi uma viagem de quatro meses na China. Neste tempo tive convic\u00e7\u00e3o que serviria ao pai em terras estrangeiras. Nesta institui\u00e7\u00e3o encontrei um lindo homem com o mesmo cora\u00e7\u00e3o, voltado para o trabalho com crian\u00e7as e adolescentes. Nos casamos e fomos nos estudar em outra escola de trabalho transcultural.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-7899 \" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2016\/08\/UltJovem_22_06_16_selo_meulugarnomundo-01-150x150.jpg\" alt=\"\" width=\"114\" height=\"114\" srcset=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2016\/08\/UltJovem_22_06_16_selo_meulugarnomundo-01-150x150.jpg 150w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/2016\/08\/UltJovem_22_06_16_selo_meulugarnomundo-01-80x80.jpg 80w\" sizes=\"auto, (max-width: 114px) 100vw, 114px\" \/><\/p>\n<p>Finalmente, depois de mais de 15 anos daquela primeira conversa com o Pai, partimos para as \u201cTerras de Al\u00e9m-Mar\u201d, de mudan\u00e7a. Neste tempo n\u00e3o \u00e9ramos apenas dois, mas sim, quatro. T\u00ednhamos duas lindas crian\u00e7as conosco!<\/p>\n<p>Hoje moramos h\u00e1 um pouco mais de tr\u00eas anos na \u00c1sia Central. Trabalhamos com esporte em uma vila com crian\u00e7as e adolescentes, e tamb\u00e9m com aconselhamento em um abrigo para meninas.<\/p>\n<p>Descobri o amor pela educa\u00e7\u00e3o depois da necessidade de alfabetizar meu filho em portugu\u00eas. O processo com minha filha est\u00e1 apenas come\u00e7ando&#8230; e que alegria! Me sinto privilegiada por servir ao Senhor a partir do meu lar at\u00e9 aos confins da Terra!<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022 <strong>Luciana<\/strong>, 36 anos, casada, m\u00e3e de dois filhos, natural de Manaus-AM e criada em Goi\u00e2nia-GO. Veterin\u00e1ria por forma\u00e7\u00e3o, educadora por voca\u00e7\u00e3o e serva do Senhor por onde ele levar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Leia mais:\u00a0<\/strong><br \/>\n\u00bb <a href=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/2019\/06\/26\/mas-os-planos-de-deus-sao-outros\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mas os planos de Deus s\u00e3o outros<\/a><br \/>\n\u00bb <a href=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/2019\/10\/23\/entre-sermoes-e-sorrisos-levando-o-evangelho-pela-graca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Entre serm\u00f5es e sorrisos: levando o evangelho pela gra\u00e7a!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Luciana Brito<br \/>\nPassei minha inf\u00e2ncia e adolesc\u00eancia entre idas \u00e0 escola dominical, acampamentos e viagens ao interior para o s\u00edtio da fam\u00edlia. Perfil muito comum de fam\u00edlias da f\u00e9 em Goi\u00e1s.<br \/>\nPor\u00e9m, aos quinze anos, tive uma breve no\u00e7\u00e3o do que estava preparado para mim. Deus falou comigo que me levaria para lugares distantes e que [&#8230;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[30642],"tags":[8441,23107,30642,16533],"class_list":["post-14453","post","type-post","status-publish","format-standard","hentry","category-o-meu-lugar-no-mundo","tag-familia","tag-missoes-transculturais","tag-o-meu-lugar-no-mundo","tag-vocacao"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/14453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/comments?post=14453"}],"version-history":[{"count":3,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/14453\/revisions"}],"predecessor-version":[{"id":14457,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/14453\/revisions\/14457"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/media?parent=14453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/categories?post=14453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/tags?post=14453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}