{"id":12773,"date":"2019-05-13T11:25:21","date_gmt":"2019-05-13T13:25:21","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/?p=12773"},"modified":"2019-08-20T13:48:55","modified_gmt":"2019-08-20T15:48:55","slug":"de-dostoievski-a-isaias-dos-hinos-tradicionais-ao-discurso-moralista-as-influencias-do-meio-evangelico","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/2019\/05\/13\/de-dostoievski-a-isaias-dos-hinos-tradicionais-ao-discurso-moralista-as-influencias-do-meio-evangelico\/","title":{"rendered":"De Dostoi\u00e9vski a Isa\u00edas, dos hinos tradicionais ao discurso moralista: as influ\u00eancias do meio evang\u00e9lico"},"content":{"rendered":"<h4><strong><span style=\"color: #993300;\">Na varanda com o autor | Gladir Cabral<\/span><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12778\" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladirDSC02868-300x200.jpg\" alt=\"\" width=\"350\" height=\"233\" srcset=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladirDSC02868-300x200.jpg 300w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladirDSC02868-768x511.jpg 768w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladirDSC02868-1024x681.jpg 1024w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladirDSC02868-732x487.jpg 732w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladirDSC02868-1140x758.jpg 1140w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladirDSC02868.jpg 1200w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>\u00c9 bem prov\u00e1vel que o leitor j\u00e1 tenha cantarolado algum verso ou a composi\u00e7\u00e3o inteira do nosso entrevistado. E, tamb\u00e9m sem ligar o nome ao autor-compositor, ouviu em algum casamento, numa roda de m\u00fasica ou na boca de m\u00fasicos conhecidos algumas das suas can\u00e7\u00f5es cheias de poesia e verdades b\u00edblicas. Gladir Cabral \u00e9 colunista da revista Ultimato, na se\u00e7\u00e3o &#8220;Literatura e Cultura&#8221;, m\u00fasico, pastor e professor de letras na Universidade do Extremo Sul Catarinense (Unesc).&nbsp;<\/p>\n<p><strong>Na Varanda com o Autor<\/strong> recebe hoje um dos poetas da igreja brasileira da atualidade. Um papo cheio de bom gosto e sensibilidade cultural, com uma riqueza enorme de indica\u00e7\u00f5es de leitura, dicas e boas influ\u00eancias para a nem sempre f\u00e1cil rela\u00e7\u00e3o entre f\u00e9 crist\u00e3 e cultura brasileira.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Alguma pessoa ou livro, em especial, influenciou sua aproxima\u00e7\u00e3o da leitura e da escrita?<\/strong><\/h4>\n<p>\u00c9 praticamente imposs\u00edvel detectar todas as influ\u00eancias que recebemos na vida. Elas veem de todos os lados e em todos os momentos. No meu caso, poderia citar, na escrita, os v\u00e1rios poetas que venho lendo ao longo da vida e as v\u00e1rias can\u00e7\u00f5es que venho ouvindo. Poetas e cantores populares s\u00e3o duas fontes inesgot\u00e1veis de inspira\u00e7\u00e3o para a sensibilidade po\u00e9tica. Quando uma can\u00e7\u00e3o me toca de verdade, sinto imediata vontade de compor, um impulso quase incontrol\u00e1vel. Saio cantarolando pela cal\u00e7ada, improvisando versos, rabiscando versos numa folha de papel. O mesmo ocorre quando leio um verso vibrante de um poema.<\/p>\n<p>Entre os escritores que mais marcaram-me a mente e o cora\u00e7\u00e3o, destaco Cruz e Souza, Casimiro de Abreu, Dostoi\u00e9vski, Drummond, Bandeira, Vin\u00edcius, Ad\u00e9lia, Cec\u00edlia Meireles, Jorge de Lima, Guimar\u00e3es Rosa, Robert Frost, Maya Angelou, Walt Whitman, Fernando Pessoa, Mark Twain, Dylan Thomas&#8230; Acho que essa lista n\u00e3o tem fim. Mas \u00e9 preciso colorir a imagina\u00e7\u00e3o com alguns exemplos de como a palavra escrita com arte e criatividade pode afetar a vida de um ser humano. Quando li <em>Recorda\u00e7\u00f5es da Casa dos Mortos<\/em>, de Dostoi\u00e9vski, tinha 18 anos, e minha cabe\u00e7a virou de cabe\u00e7a para baixo ao conviver com o narrador e seus companheiros de pris\u00e3o nos invernos da Sib\u00e9ria. Logo em seguida descobria Alexander Soljen\u00edtsin. Pronto, leria toda a s\u00e9rie do<em> O Arquip\u00e9lago Gulag<\/em>.<\/p>\n<p>Mas n\u00e3o s\u00f3 de linguagem em prosa vem a influ\u00eancia. A saudade cantada em versos pelos poetas rom\u00e2nticos tamb\u00e9m me marcou. Nunca imaginei que, ao ler \u201cMinha terra tem palmeiras como canta o sabi\u00e1\u201d, estaria lendo um poema que seria t\u00e3o citado na literatura, na m\u00fasica e na cultura popular brasileira. A linha desse poema come\u00e7a em Gon\u00e7alves Dias e apenas estaria de passagem em Casimiro de Abreu, passando por Oswald de Andrade, Murilo Mendes, Carlos Drummond, M\u00e1rio Quintana, Jos\u00e9 Paulo Paes, Chico Buarque e Tom Jobim. Pronto, a poesia me havia feito ref\u00e9m.<\/p>\n<p>Mas claro, \u00e9 preciso lembrar que eu j\u00e1 estava predisposto a ser tocado pela poesia, visto que minha cria\u00e7\u00e3o foi no protestantismo hist\u00f3rico, com direito a muitas leituras dos Salmos, Cantares, os profetas, e todos livros hist\u00f3ricos da B\u00edblia. O te\u00f3logo Walter Brueggemann observa que todos os profetas do Velho Testamento eram poetas. Ler Isa\u00edas \u00e9 ler poesia. Al\u00e9m disso, aprendi a cantar todos os hinos tradicionais, mesmo quando \u201cHomem bom, doce \u00e0 f\u00e9\u201d me chegava como \u201cHomem bom, d\u00e1 caf\u00e9\u201d&#8230; rs. Isso para n\u00e3o falar do \u201cSe, da vida, as vagas procelosas s\u00e3o&#8230;\u201d, cujo significado eu n\u00e3o acessava. Mas n\u00e3o importava, tinha a m\u00fasica, o ritmo de marcha e estribilho, que volta e meio surge-me \u00e0 mente.<\/p>\n<p>Anos mais tarde, a forma\u00e7\u00e3o teol\u00f3gica me permitiu conhecer Dietrich Bonhoeffer, Rubem Alves, Thomas Kelly, John Donne, John Bunyan, Albert Schweitzer, Emil Brunner, Carlos Mesters e outros. Depois, os estudos liter\u00e1rios me apresentariam autores ingleses, norte-americanos e canadenses. Alumbramento.<\/p>\n<p>Nem vou falar das can\u00e7\u00f5es populares que me marcaram. Deixo isso para outro texto, outra entrevista, pois s\u00e3o muitos e diversos.<\/p>\n<h4><strong>Quando a inspira\u00e7\u00e3o para escrever n\u00e3o vem\u2026<\/strong><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12267 alignright\" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/selo_navaranda-300x75.jpg\" alt=\"\" width=\"300\" height=\"75\" srcset=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/selo_navaranda-300x75.jpg 300w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/selo_navaranda.jpg 402w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Quando a inspira\u00e7\u00e3o n\u00e3o vem, que fazer? O melhor \u00e9 dar uma boa caminhada, ler, ouvir uma can\u00e7\u00e3o, tirar uma soneca, desviar o foco do muro intranspon\u00edvel que \u00e9 a folha de papel em branco. Com o tempo, fui aprendendo a estabelecer algumas estrat\u00e9gias de enfrentamento do bloqueio de escrita: tenho sempre comigo um bloco de anota\u00e7\u00f5es onde rabisco minhas ideias para textos, can\u00e7\u00f5es, poemas, ensaios, serm\u00f5es, projetos de pesquisa&#8230; Costumo usar a t\u00e9cnica do mapa conceitual para rabiscar ideias para textos. Costumo tamb\u00e9m escrever palavras que tenham uma associa\u00e7\u00e3o. Vou fazendo uma lista aparentemente aleat\u00f3ria de palavras que est\u00e3o ligadas entre si, tipo janela, vidro, varanda, alpendre, fazenda, porteira&#8230; e por a\u00ed vai. Isso geralmente me d\u00e1 as palavras que poderei usar na can\u00e7\u00e3o, no poema ou no artigo que estou escrevendo. Agora, quando estou sem ideias, desvio o foco para outra coisa. N\u00e3o fico malhando em ferro frio. N\u00e3o fa\u00e7o uma can\u00e7\u00e3o s\u00f3 porque tenho que fazer uma can\u00e7\u00e3o. Claro que isso \u00e0s vezes me joga no limite da data de entrega de um trabalho, por exemplo. A\u00ed n\u00e3o tem jeito. Alguns textos nascem a f\u00f3rceps. Felizmente, n\u00e3o todos.<\/p>\n<h4><strong>O que os adultos devem ler para as crian\u00e7as?<\/strong><\/h4>\n<p>Hoje, felizmente, a literatura infantil brasileira est\u00e1 repleta de autores e obras de grande import\u00e2ncia nacional e internacional. H\u00e1 sempre uma grande quantidade de autores novos publicando seus trabalhos, alguns com grande \u00eaxito, mas eu gostaria de lembrar os autores que j\u00e1 se tornaram cl\u00e1ssicos: Ruth Rocha \u00e9 fundamental, assim como Ziraldo, Ana Maria Machado, al\u00e9m de Clara Maria Machado, Lygia Bojunga, Tatiana Belinky, Eva Furnari e at\u00e9 as conhecid\u00edssimas Cec\u00edlia Meireles e Clarice Lispector. Ruth Rocha, por exemplo, \u00e9 grande mestra da forma\u00e7\u00e3o humana da crian\u00e7a, a no\u00e7\u00e3o de vida coletiva, de respeito ao outro, a quest\u00e3o do poder e da viol\u00eancia, da repress\u00e3o e do sonho de liberdade. Literatura infantil \u00e9 coisa muito s\u00e9ria. Recomendaria tamb\u00e9m nosso querido C.S. Lewis e seus contos de N\u00e1rnia, que n\u00e3o ficam para tr\u00e1s de nenhuma grande obra da literatura mundial. Li tardiamente, mas recomendo muito os contos de Hans Christian Andersen, cheios de profundidade, sensibilidade e densidade.<\/p>\n<h4><strong>Que conselho voc\u00ea gostaria de ter recebido na sua juventude?<\/strong><\/h4>\n<p>Na juventude, gostaria que me tivessem dito para ler mais e melhor. Gostaria que me avisassem para aproveitar o tempo com as pessoas mais velhas e experientes na leitura de mundo, pois rapidamente elas partiriam. Eu teria aproveitado mais a biblioteca do Semin\u00e1rio Presbiteriano de Campinas, por exemplo, ou as oportunidades que tive de conversar com Rubem Alves, J\u00falio Andrade Ferreira, L\u00e1zaro Lopes de Arruda, meu professor de hist\u00f3ria da igreja, que era poeta e apaixonado pela poesia caipira brasileira, e outras tantas pessoas que conheci ao longo da vida.<\/p>\n<h4><strong>Como voc\u00ea lida com o envelhecer?<\/strong><\/h4>\n<div id=\"attachment_12798\" style=\"width: 360px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-12798\" class=\"wp-image-12798\" src=\"http:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladir_Ruth-minha-esposa-e-minhas-filhas-Johana-e-Julia-300x200.jpg\" alt=\"\" width=\"350\" height=\"234\" srcset=\"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladir_Ruth-minha-esposa-e-minhas-filhas-Johana-e-Julia-300x200.jpg 300w, https:\/\/ultimato.com.br\/sites\/blogdaultimato\/files\/blog_ult_24_04_2019_na-varanda-gladir_Ruth-minha-esposa-e-minhas-filhas-Johana-e-Julia.jpg 700w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-12798\" class=\"wp-caption-text\">Gladir, sua esposa Ruth e as filhas Johana e Julia<\/p><\/div>\n<p>Ainda estou aprendendo essa li\u00e7\u00e3o, agora em aulas mais intensivas. A velocidade com que o tempo passa nos deixa atordoados. Um poeta da minha terra certa vez escreveu: \u201cA nuvem que passa deixa uma sobra que passa no rio que passa\u201d. Cada vez me assusto mais com essa verdade. O fluxo da vida \u00e9 r\u00e1pido e, como diz o salmista, somos como um sopro, um sonho. A literatura fala muito sobre a finitude e a velhice. Tenho aprendido muito com <em>Rei Lear<\/em>, de Shakespeare,<em> A Vida \u00e9 Sonho<\/em>, de Pedro Calder\u00f3n de la Barca, mas tamb\u00e9m com Quintana, Cec\u00edlia, Cora Coralina, Manoel de Barros. O envelhecer tem suas belezas, como o p\u00f4r-do-sol, uma delas \u00e9 o conhecimento e as li\u00e7\u00f5es que vamos aprendendo com a vida.<\/p>\n<p>Uma das li\u00e7\u00f5es mais importantes, diria Elizabeth Bishop, \u00e9 aprender a perder as coisas, pouco a pouco, uma chave, uma casa, uma pessoa que se ama. Li\u00e7\u00e3o nada f\u00e1cil. Outro desafio que a velhice nos traz \u00e9 a limita\u00e7\u00e3o f\u00edsica. \u00c9 preciso preparar-se para isso, fazer a li\u00e7\u00e3o de casa, exerc\u00edcios f\u00edsicos, dieta saud\u00e1vel, caminhadas&#8230; \u00c9 preciso tamb\u00e9m reinventar-se sempre, encontrar novas vers\u00f5es de si mesmo, aprender sempre, at\u00e9 o fim. Ao fim, \u00e9 bom lembrar, como disse certa vez o ap\u00f3stolo Paulo, nosso interior pode n\u00e3o envelhecer, mesmo que nosso exterior se corrompa. Nesse sentido, pode haver gente idosa com 24 anos de idade, a mente fechada, pensamento conservador, formal, travado. E pode haver gente feito nosso querido Rev. Elben, oitenta anos no corpo, 30 anos na mente, sempre aprendendo, sempre pensando, sempre rindo, sobretudo de si mesmo.<\/p>\n<h4><strong>O que mais o anima e o que mais o incomoda no meio evang\u00e9lico?<\/strong><\/h4>\n<p>O que mais me anima \u00e9 sua rica heran\u00e7a reflexiva, de exerc\u00edcio da leitura, de belos hinos, de \u00eanfase na vida devocional, de cuidado de si, de escrita (sobretudo a escrita de si), mas tamb\u00e9m da leitura. No entanto, no nosso caso do Brasil, h\u00e1 coisas que me incomodam muito nessa heran\u00e7a: nosso individualismo fundamental, que \u00e0s vezes se traduz em desprezo pelas quest\u00f5es sociais e hist\u00f3ricas de nosso tempo, o discurso moralista t\u00e3o cheio de contradi\u00e7\u00e3o que j\u00e1 afastou tanta gente do evangelho, o esp\u00edrito de conservadorismo pol\u00edtico que se revelou quando os evang\u00e9licos apoiaram o golpe militar de 64, por exemplo, e a ditadura que se estabeleceu posteriormente, e agora a decep\u00e7\u00e3o com os evang\u00e9licos que definiram os rumos do pa\u00eds ao ajudarem a eleger o presente governo. Como pode, um povo que segue a Cristo apoiar gente que elogia torturadores e que tem um discurso t\u00e3o violento de \u00f3dio e intoler\u00e2ncia? Como pode os evang\u00e9licos apoiarem discursos de ignor\u00e2ncia e obscurantismo, n\u00f3s que aprendemos tanto sobre a liberdade de pensamento e a busca do conhecimento.<\/p>\n<p>Tudo isso me cansa muito. Sei que h\u00e1 exce\u00e7\u00f5es e quero me lembrar delas, pois me inspiram a entender o que \u00e9 ser protestante numa sociedade materialista como a nossa, o que \u00e9 ser evang\u00e9lico de verdade, num tempo em que tantos que se dizem crentes d\u00e3o p\u00e9ssimo testemunho de amor \u00e0s pessoas e ao mundo que Deus criou e nos deu para cuidar. Vivemos um tempo de ju\u00edzo. Espero que saiamos desse encantamento, dessa fascina\u00e7\u00e3o ilus\u00f3ria pelo poder.<\/p>\n<p><strong>Leia mais<br \/>\n<\/strong>\u00bb <a href=\"https:\/\/ultimato.com.br\/sites\/gladircabral\/\" target=\"_blank\" rel=\"noopener noreferrer\">Blog do Gladir<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.ultimato.com.br\/revista\/busca\/?q=literatura+e+cultura\" target=\"_blank\" rel=\"noopener noreferrer\">Se\u00e7\u00e3o &#8220;Literatura e Cultura&#8221; da revista Ultimato<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na varanda com o autor | Gladir Cabral<br \/>\n&nbsp;<br \/>\n\u00c9 bem prov\u00e1vel que o leitor j\u00e1 tenha cantarolado algum verso ou a composi\u00e7\u00e3o inteira do nosso entrevistado. E, tamb\u00e9m sem ligar o nome ao autor-compositor, ouviu em algum casamento, numa roda de m\u00fasica ou na boca de m\u00fasicos conhecidos algumas das suas can\u00e7\u00f5es cheias de poesia e [&#8230;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[32239],"tags":[184,36096],"class_list":["post-12773","post","type-post","status-publish","format-standard","hentry","category-na-varanda-com-o-autor","tag-gladir-cabral","tag-na-varanda-com-autor"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/12773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/comments?post=12773"}],"version-history":[{"count":12,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/12773\/revisions"}],"predecessor-version":[{"id":13451,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/posts\/12773\/revisions\/13451"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/media?parent=12773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/categories?post=12773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/blogdaultimato\/wp-json\/wp\/v2\/tags?post=12773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}