{"id":1634,"date":"2017-08-31T08:00:20","date_gmt":"2017-08-31T11:00:20","guid":{"rendered":"http:\/\/ultimato.com.br\/sites\/amorese\/?p=1634"},"modified":"2017-10-20T10:06:37","modified_gmt":"2017-10-20T13:06:37","slug":"sola-scriptura-em-tempos-de-pos-verdade","status":"publish","type":"post","link":"https:\/\/ultimato.com.br\/sites\/amorese\/2017\/08\/31\/sola-scriptura-em-tempos-de-pos-verdade\/","title":{"rendered":"Sola Scriptura em tempos de p\u00f3s-verdade"},"content":{"rendered":"<p><span style=\"color: #993300;\"><em>Vers\u00e3o completa do texto Sola Scriptura em tempos de &#8220;p\u00f3s-verdade&#8221;, publicado na revista <strong>Ultimato<\/strong>, edi\u00e7\u00e3o #367.<\/em><\/span><\/p>\n<p><a href=\"http:\/\/ultimato.com.br\/sites\/amorese\/files\/Ponto_final_raul-petri-135002.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1639 alignright\" src=\"http:\/\/ultimato.com.br\/sites\/amorese\/files\/Ponto_final_raul-petri-135002.jpg\" alt=\"\" width=\"380\" height=\"253\" srcset=\"https:\/\/ultimato.com.br\/sites\/amorese\/files\/Ponto_final_raul-petri-135002.jpg 380w, https:\/\/ultimato.com.br\/sites\/amorese\/files\/Ponto_final_raul-petri-135002-300x200.jpg 300w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a>Tr\u00eas hist\u00f3rias reais. Primeira: em 2016, a Oxford Dictionaries elegeu o voc\u00e1bulo \u201cp\u00f3s-verdade\u201d como a palavra do ano na l\u00edngua inglesa. Segundo a institui\u00e7\u00e3o, naquele ano houve um crescimento de 2.000% no uso do termo, um neologismo em que se admite que numa sociedade \u201cmidi\u00e1tica\u201d (mediada pela m\u00eddia) n\u00e3o existem mais fatos, apenas vers\u00f5es. A verdade, agora, depende de quem narra os fatos.<\/p>\n<p>Segunda: em uma rodinha de fim de culto, um irm\u00e3o, frustrado com a parte do serm\u00e3o que dizia que o significado de \u201cjusti\u00e7a de Deus\u201d, em Romanos, tinha a conota\u00e7\u00e3o de um processo de justifica\u00e7\u00e3o, interrompeu o papo e disse: \u201cParem com esse neg\u00f3cio de significado, conota\u00e7\u00e3o, mimimi b\u00edblico! \u00c9 o que est\u00e1 escrito e pronto! Pra qu\u00ea complicar? Est\u00e3o querendo torcer as coisas?! N\u00e3o est\u00e1 escrito: \u2018justi\u00e7a de Deus\u2019? Ent\u00e3o! \u00c9 justi\u00e7a e pronto! \u00c9 pau! \u00c9 cana!\u201d. E se retirou da conversa, como quem tinha dito a \u00faltima palavra.<\/p>\n<p>Terceira: uma pol\u00edtica evang\u00e9lica, ao incitar seu audit\u00f3rio \u00e0 luta, arrematou: \u201cPorque na minha B\u00edblia est\u00e1 escrito que sem derramamento de sangue n\u00e3o haver\u00e1 reden\u00e7\u00e3o. Vamos \u00e0 luta com quaisquer que sejam as nossas armas\u201d.<\/p>\n<p>Uma das grandes mudan\u00e7as introduzidas pela Reforma Protestante foi o livre acesso \u00e0s Escrituras, facilitado pela prensa de Gutemberg, inventada alguns anos antes, de cujo prelo saiu, como primeiro livro, a B\u00edblia Sagrada. At\u00e9 ent\u00e3o, a consulta direta \u00e0s Escrituras era dificultada por v\u00e1rios motivos, dentre os quais o analfabetismo, a inexist\u00eancia de exemplares da B\u00edblia nas igrejas e, talvez o principal, a obrigat\u00f3ria media\u00e7\u00e3o da Igreja no entendimento do texto sagrado. N\u00e3o se podia compreender uma passagem b\u00edblica de modo diferente da interpreta\u00e7\u00e3o oficial. Com isso, a tradi\u00e7\u00e3o se associou \u00e0 leitura b\u00edblica, tendo, inclusive, preval\u00eancia sobre o pr\u00f3prio texto b\u00edblico. Por exemplo, a tradi\u00e7\u00e3o diz que Jesus n\u00e3o teve irm\u00e3os. Outro exemplo: a compreens\u00e3o da afirma\u00e7\u00e3o de Jesus a Pedro: \u201cTu \u00e9s Pedro, e sobre essa pedra edificarei a minha igreja\u201d fixou-se como a institui\u00e7\u00e3o do primeiro papa. Para os reformadores, essa \u201cpedra\u201d refere-se \u00e0 afirma\u00e7\u00e3o de Pedro: \u201cTu \u00e9s o Cristo, filho do Deus vivo\u201d (Mt 16.16-18).<\/p>\n<p><!--more--><\/p>\n<p>O movimento de livre acesso \u00e0s Escrituras evoluiu, com Lutero e seus sucessores, para o direito ao foro \u00edntimo, no contato com elas, entendendo-se que Deus nos d\u00e1 a compreens\u00e3o por meio do Esp\u00edrito Santo. E mais, chegou-se \u00e0 afirma\u00e7\u00e3o de que somente as Escrituras s\u00e3o verdade e autoridade sobre quest\u00f5es de f\u00e9 e pr\u00e1tica: <em>sola Scriptura<\/em> \u2013 tudo o que se disse ou que se venha a dizer sobre essas quest\u00f5es dever\u00e1 passar pelo crivo das Escrituras.<\/p>\n<p>A essas alturas, o \u201cdossel sagrado\u201d \u2013 express\u00e3o de Peter Berger, falecido em julho de 2017 \u2013 j\u00e1 se desfazia. Aquela c\u00fapula simb\u00f3lica que mantinha a vis\u00e3o do mundo e a interpreta\u00e7\u00e3o dos fatos da hist\u00f3ria e do cotidiano \u00fanicas, coesas e imut\u00e1veis \u2013 se preciso, com o uso da espada \u2013 come\u00e7a a ruir, para dar lugar ao pluralismo iluminista. Desde ent\u00e3o, a cada dia existe menos consenso sobre um n\u00famero maior de coisas. Em cada cabe\u00e7a, uma senten\u00e7a; em cada cora\u00e7\u00e3o, uma verdade.<\/p>\n<p>E os fatos? Ora, os fatos!<\/p>\n<p>N\u00e3o muitos s\u00e9culos passados, vivemos a era da \u201cp\u00f3s-verdade\u201d. Mesmo em termos de f\u00e9. Mesmo em termos de doutrinas b\u00edblicas, ou crist\u00e3s; mesmo entre os reformados, ou evang\u00e9licos. Sim, numa mesma denomina\u00e7\u00e3o; numa mesma igreja; numa mesma fam\u00edlia. Maior que os fatos b\u00edblicos (se \u00e9 que temos acesso a eles, dir\u00e1 a \u201cp\u00f3s-verdade\u201d) \u00e9 a forma como os interpretamos, a narrativa \u00e0 qual os ajustamos para dar suporte \u00e0s nossas percep\u00e7\u00f5es espirituais.<\/p>\n<p>E o que restou da s\u00f3lida \u201cc\u00fapula sagrada\u201d? Do antigo evangelho? Da palavra da verdade?<\/p>\n<p>Bem, das r\u00edgidas estruturas de imposi\u00e7\u00e3o e manuten\u00e7\u00e3o do cristianismo medieval restou pouco. Inclusive entre os cat\u00f3licos. Do antigo evangelho, ainda hoje <em>best-seller<\/em> incontest\u00e1vel, surgiram primorosas tradu\u00e7\u00f5es, vers\u00f5es e coment\u00e1rios, em centenas de l\u00ednguas e linguagens; o melhor dos mundos. E da palavra da verdade permanece, misterioso e intocado, o poder de Deus \u201cpara a salva\u00e7\u00e3o de todo aquele que cr\u00ea\u201d. Ela ainda salva, redime e santifica! E nos leva a dizer em nossos cora\u00e7\u00f5es: \u201cSenhor Jesus!\u201d e a cuidar do pobre, da crian\u00e7a, da vi\u00fava e do estrangeiro. Para esse fen\u00f4meno pode haver muitas vers\u00f5es. Mas n\u00e3o \u201cp\u00f3s-verdade\u201d.<\/p>\n<p><strong>\u2022 Rubem Amorese<\/strong> \u00e9 presb\u00edtero na Igreja Presbiteriana do Planalto, em Bras\u00edlia. Foi professor na Faculdade Teol\u00f3gica Batista por vinte anos e tamb\u00e9m consultor legislativo no Senado Federal. \u00c9 autor de, entre outros, <em>F\u00e1brica de Mission\u00e1rios <\/em>e <em>Ponto Final<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vers\u00e3o completa do texto Sola Scriptura em tempos de &#8220;p\u00f3s-verdade&#8221;, publicado na revista Ultimato, edi\u00e7\u00e3o #367.<br \/>\nTr\u00eas hist\u00f3rias reais. Primeira: em 2016, a Oxford Dictionaries elegeu o voc\u00e1bulo \u201cp\u00f3s-verdade\u201d como a palavra do ano na l\u00edngua inglesa. Segundo a institui\u00e7\u00e3o, naquele ano houve um crescimento de 2.000% no uso do termo, um neologismo em que se [&#8230;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119],"tags":[32231,5935,35349,35347],"class_list":["post-1634","post","type-post","status-publish","format-standard","hentry","category-na-ultimato","tag-mais-na-internet","tag-reforma","tag-sola-scriptura","tag-ult367"],"_links":{"self":[{"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/posts\/1634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/comments?post=1634"}],"version-history":[{"count":5,"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/posts\/1634\/revisions"}],"predecessor-version":[{"id":1656,"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/posts\/1634\/revisions\/1656"}],"wp:attachment":[{"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/media?parent=1634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/categories?post=1634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimato.com.br\/sites\/amorese\/wp-json\/wp\/v2\/tags?post=1634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}